{"id":12222,"date":"2025-02-27T19:51:46","date_gmt":"2025-02-27T18:51:46","guid":{"rendered":"https:\/\/spainfilmcommission.com\/?post_type=localizacion&#038;p=12222"},"modified":"2025-04-21T12:58:59","modified_gmt":"2025-04-21T10:58:59","slug":"batan-de-pradoluengo","status":"publish","type":"localizacion","link":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/batan-de-pradoluengo\/","title":{"rendered":"Bat\u00e1n de Pradoluengo"},"content":{"rendered":"","protected":false},"author":2,"template":"","meta":[],"class_list":["post-12222","localizacion","type-localizacion","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rodar en Bat\u00e1n de Pradoluengo - Spain Film Commission<\/title>\n<meta name=\"description\" content=\"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Bat\u00e1n de Pradoluengo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/spainfilmcommission.com\/en\/ai-locations\/batan-de-pradoluengo\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rodar en Bat\u00e1n de Pradoluengo - Spain Film Commission\" \/>\n<meta property=\"og:description\" content=\"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Bat\u00e1n de Pradoluengo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/spainfilmcommission.com\/en\/ai-locations\/batan-de-pradoluengo\/\" \/>\n<meta property=\"og:site_name\" content=\"Spain Film Commission\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-21T10:58:59+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/ai-locations\\\/batan-de-pradoluengo\\\/\",\"url\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/ai-locations\\\/batan-de-pradoluengo\\\/\",\"name\":\"Rodar en Bat\u00e1n de Pradoluengo - Spain Film Commission\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#website\"},\"datePublished\":\"2025-02-27T18:51:46+00:00\",\"dateModified\":\"2025-04-21T10:58:59+00:00\",\"description\":\"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Bat\u00e1n de Pradoluengo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/ai-locations\\\/batan-de-pradoluengo\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/ai-locations\\\/batan-de-pradoluengo\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/ai-locations\\\/batan-de-pradoluengo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bat\u00e1n de Pradoluengo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/\",\"name\":\"Spain Film Commission\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#organization\",\"name\":\"Spain Film Commission\",\"url\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/spainfilmcommission.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/SPC_COLOR.png\",\"contentUrl\":\"https:\\\/\\\/spainfilmcommission.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/SPC_COLOR.png\",\"width\":1665,\"height\":1665,\"caption\":\"Spain Film Commission\"},\"image\":{\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rodar en Bat\u00e1n de Pradoluengo - Spain Film Commission","description":"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Bat\u00e1n de Pradoluengo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/batan-de-pradoluengo\/","og_locale":"en_US","og_type":"article","og_title":"Rodar en Bat\u00e1n de Pradoluengo - Spain Film Commission","og_description":"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Bat\u00e1n de Pradoluengo","og_url":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/batan-de-pradoluengo\/","og_site_name":"Spain Film Commission","article_modified_time":"2025-04-21T10:58:59+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/batan-de-pradoluengo\/","url":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/batan-de-pradoluengo\/","name":"Rodar en Bat\u00e1n de Pradoluengo - Spain Film Commission","isPartOf":{"@id":"https:\/\/spainfilmcommission.com\/en\/#website"},"datePublished":"2025-02-27T18:51:46+00:00","dateModified":"2025-04-21T10:58:59+00:00","description":"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Bat\u00e1n de Pradoluengo","breadcrumb":{"@id":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/batan-de-pradoluengo\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/spainfilmcommission.com\/en\/ai-locations\/batan-de-pradoluengo\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/batan-de-pradoluengo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/spainfilmcommission.com\/en\/"},{"@type":"ListItem","position":2,"name":"Bat\u00e1n de Pradoluengo"}]},{"@type":"WebSite","@id":"https:\/\/spainfilmcommission.com\/en\/#website","url":"https:\/\/spainfilmcommission.com\/en\/","name":"Spain Film Commission","description":"","publisher":{"@id":"https:\/\/spainfilmcommission.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/spainfilmcommission.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/spainfilmcommission.com\/en\/#organization","name":"Spain Film Commission","url":"https:\/\/spainfilmcommission.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/spainfilmcommission.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2024\/07\/SPC_COLOR.png","contentUrl":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2024\/07\/SPC_COLOR.png","width":1665,"height":1665,"caption":"Spain Film Commission"},"image":{"@id":"https:\/\/spainfilmcommission.com\/en\/#\/schema\/logo\/image\/"}}]}},"socio":[{"ID":"32","user_login":"burgos-film-commission","user_nicename":"burgos-film-commission","display_name":"burgos-film-commission","user_pass":"****************","user_email":"info@burgosfilmcommission.org","user_url":"","user_registered":"2024-12-19 16:05:18","id":32}],"nombrees":"Bat\u00e1n de Pradoluengo","nombreen":"Pradoluengo fulling","localidad":"Pradoluengo","provincia":"Burgos","coordenadas_maps":",","latitud":[],"longitud":[],"direcciones":"","direccionen":"","cod_postal":[],"telefono":"","fax":"","mail":"","web":"http:\/\/www.burgosfilmcommission.org\/","descripciones":"Antigua instalaci\u00f3n textil repleta de maquinaria y elementos para la fabricaci\u00f3n de calcetines y otras prendas. Supone todo un muestrario de vestigios de una industria floreciente del Siglo XX","descripcionen":"Old textile facility full of machinery and elements for the manufacture of socks and other garments. It is a showcase of vestiges of a flourishing industry of the twentieth century.","galeria":[{"ID":"26507","post_author":"2","post_date":"2025-03-08 11:56:39","post_date_gmt":"2025-03-08 10:56:39","post_content":"","post_title":"foto-1201_9792","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"foto-1201_9792","to_ping":"","pinged":"","post_modified":"2025-04-21 12:58:59","post_modified_gmt":"2025-04-21 10:58:59","post_content_filtered":"","post_parent":"12222","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/foto-1201_9792.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"26507"},{"ID":"26509","post_author":"2","post_date":"2025-03-08 11:56:41","post_date_gmt":"2025-03-08 10:56:41","post_content":"","post_title":"foto-1201_9793","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"foto-1201_9793","to_ping":"","pinged":"","post_modified":"2025-04-21 12:58:59","post_modified_gmt":"2025-04-21 10:58:59","post_content_filtered":"","post_parent":"12222","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/foto-1201_9793.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"26509"},{"ID":"26511","post_author":"2","post_date":"2025-03-08 11:56:43","post_date_gmt":"2025-03-08 10:56:43","post_content":"","post_title":"foto-1201_9794","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"foto-1201_9794","to_ping":"","pinged":"","post_modified":"2025-04-21 12:58:59","post_modified_gmt":"2025-04-21 10:58:59","post_content_filtered":"","post_parent":"12222","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/foto-1201_9794.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"26511"},{"ID":"26513","post_author":"2","post_date":"2025-03-08 11:56:45","post_date_gmt":"2025-03-08 10:56:45","post_content":"","post_title":"foto-1201_9795","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"foto-1201_9795","to_ping":"","pinged":"","post_modified":"2025-04-21 12:58:59","post_modified_gmt":"2025-04-21 10:58:59","post_content_filtered":"","post_parent":"12222","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/foto-1201_9795.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"26513"},{"ID":"26515","post_author":"2","post_date":"2025-03-08 11:56:46","post_date_gmt":"2025-03-08 10:56:46","post_content":"","post_title":"foto-1201_9796","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"foto-1201_9796","to_ping":"","pinged":"","post_modified":"2025-04-21 12:58:59","post_modified_gmt":"2025-04-21 10:58:59","post_content_filtered":"","post_parent":"12222","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/foto-1201_9796.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"26515"}],"nombrepaginaes":"batan-de-pradoluengo","nombrepaginaen":"pradoluengo-fulling","latitud_gps":"","longitud_gps":"","adicionaleses":"","adicionalesen":"","videoes":"","videoen":"","video2es":"","video2en":"","_links":{"self":[{"href":"https:\/\/spainfilmcommission.com\/en\/wp-json\/wp\/v2\/localizaciones\/localizacion\/12222","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/spainfilmcommission.com\/en\/wp-json\/wp\/v2\/localizaciones\/localizacion"}],"about":[{"href":"https:\/\/spainfilmcommission.com\/en\/wp-json\/wp\/v2\/types\/localizacion"}],"author":[{"embeddable":true,"href":"https:\/\/spainfilmcommission.com\/en\/wp-json\/wp\/v2\/users\/2"}],"wp:attachment":[{"href":"https:\/\/spainfilmcommission.com\/en\/wp-json\/wp\/v2\/media?parent=12222"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}