{"id":12145,"date":"2025-02-27T19:51:46","date_gmt":"2025-02-27T18:51:46","guid":{"rendered":"https:\/\/spainfilmcommission.com\/?post_type=localizacion&#038;p=12145"},"modified":"2025-04-21T13:51:13","modified_gmt":"2025-04-21T11:51:13","slug":"plaza-del-ayuntamiento","status":"publish","type":"localizacion","link":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/plaza-del-ayuntamiento\/","title":{"rendered":"Plaza del Ayuntamiento"},"content":{"rendered":"","protected":false},"author":2,"template":"","meta":[],"class_list":["post-12145","localizacion","type-localizacion","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rodar en Plaza del Ayuntamiento - Spain Film Commission<\/title>\n<meta name=\"description\" content=\"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Plaza del Ayuntamiento\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/spainfilmcommission.com\/en\/ai-locations\/plaza-del-ayuntamiento\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rodar en Plaza del Ayuntamiento - Spain Film Commission\" \/>\n<meta property=\"og:description\" content=\"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Plaza del Ayuntamiento\" \/>\n<meta property=\"og:url\" content=\"https:\/\/spainfilmcommission.com\/en\/ai-locations\/plaza-del-ayuntamiento\/\" \/>\n<meta property=\"og:site_name\" content=\"Spain Film Commission\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-21T11:51:13+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/ai-locations\\\/plaza-del-ayuntamiento\\\/\",\"url\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/ai-locations\\\/plaza-del-ayuntamiento\\\/\",\"name\":\"Rodar en Plaza del Ayuntamiento - Spain Film Commission\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#website\"},\"datePublished\":\"2025-02-27T18:51:46+00:00\",\"dateModified\":\"2025-04-21T11:51:13+00:00\",\"description\":\"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Plaza del Ayuntamiento\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/ai-locations\\\/plaza-del-ayuntamiento\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/ai-locations\\\/plaza-del-ayuntamiento\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/ai-locations\\\/plaza-del-ayuntamiento\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Plaza del Ayuntamiento\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/\",\"name\":\"Spain Film Commission\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#organization\",\"name\":\"Spain Film Commission\",\"url\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/spainfilmcommission.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/SPC_COLOR.png\",\"contentUrl\":\"https:\\\/\\\/spainfilmcommission.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/SPC_COLOR.png\",\"width\":1665,\"height\":1665,\"caption\":\"Spain Film Commission\"},\"image\":{\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rodar en Plaza del Ayuntamiento - Spain Film Commission","description":"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Plaza del Ayuntamiento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/plaza-del-ayuntamiento\/","og_locale":"en_US","og_type":"article","og_title":"Rodar en Plaza del Ayuntamiento - Spain Film Commission","og_description":"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Plaza del Ayuntamiento","og_url":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/plaza-del-ayuntamiento\/","og_site_name":"Spain Film Commission","article_modified_time":"2025-04-21T11:51:13+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/plaza-del-ayuntamiento\/","url":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/plaza-del-ayuntamiento\/","name":"Rodar en Plaza del Ayuntamiento - Spain Film Commission","isPartOf":{"@id":"https:\/\/spainfilmcommission.com\/en\/#website"},"datePublished":"2025-02-27T18:51:46+00:00","dateModified":"2025-04-21T11:51:13+00:00","description":"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Plaza del Ayuntamiento","breadcrumb":{"@id":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/plaza-del-ayuntamiento\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/spainfilmcommission.com\/en\/ai-locations\/plaza-del-ayuntamiento\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/plaza-del-ayuntamiento\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/spainfilmcommission.com\/en\/"},{"@type":"ListItem","position":2,"name":"Plaza del Ayuntamiento"}]},{"@type":"WebSite","@id":"https:\/\/spainfilmcommission.com\/en\/#website","url":"https:\/\/spainfilmcommission.com\/en\/","name":"Spain Film Commission","description":"","publisher":{"@id":"https:\/\/spainfilmcommission.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/spainfilmcommission.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/spainfilmcommission.com\/en\/#organization","name":"Spain Film Commission","url":"https:\/\/spainfilmcommission.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/spainfilmcommission.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2024\/07\/SPC_COLOR.png","contentUrl":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2024\/07\/SPC_COLOR.png","width":1665,"height":1665,"caption":"Spain Film Commission"},"image":{"@id":"https:\/\/spainfilmcommission.com\/en\/#\/schema\/logo\/image\/"}}]}},"socio":[{"ID":"13","user_login":"alicante-film-office","user_nicename":"alicante-film-office","display_name":"alicante-film-office","user_pass":"****************","user_email":"info@alicantefilmoffice.com","user_url":"","user_registered":"2024-12-19 13:32:16","id":13}],"nombrees":"Plaza del Ayuntamiento","nombreen":"Town Hall square","localidad":"Alicante","provincia":"Alicante","coordenadas_maps":"38.34537242464624, -0.4806525962915882","latitud":"38.345372424646","longitud":"-0.480652596292","direcciones":"","direccionen":"","cod_postal":[],"telefono":"","fax":"","mail":"","web":"https:\/\/www.alicantefilmoffice.com\/localizacion\/ayuntamiento-de-alicante\/","descripciones":"Los arcos\u00a0que\u00a0rodean la plaza y el edificio Consistorial conforman\u00a0uno de los espacios con car\u00e1cter hist\u00f3rico y al aire libre de la ciudad.","descripcionen":"","galeria":[{"ID":"25691","post_author":"2","post_date":"2025-03-08 11:42:47","post_date_gmt":"2025-03-08 10:42:47","post_content":"","post_title":"foto-1123_10534","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"foto-1123_10534","to_ping":"","pinged":"","post_modified":"2025-04-21 13:51:13","post_modified_gmt":"2025-04-21 11:51:13","post_content_filtered":"","post_parent":"12145","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/foto-1123_10534.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"25691"},{"ID":"25693","post_author":"2","post_date":"2025-03-08 11:42:49","post_date_gmt":"2025-03-08 10:42:49","post_content":"","post_title":"foto-1123_10535","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"foto-1123_10535","to_ping":"","pinged":"","post_modified":"2025-04-21 13:51:13","post_modified_gmt":"2025-04-21 11:51:13","post_content_filtered":"","post_parent":"12145","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/foto-1123_10535.jpeg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"25693"},{"ID":"25695","post_author":"2","post_date":"2025-03-08 11:42:51","post_date_gmt":"2025-03-08 10:42:51","post_content":"","post_title":"foto-1123_10536","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"foto-1123_10536","to_ping":"","pinged":"","post_modified":"2025-04-21 13:51:13","post_modified_gmt":"2025-04-21 11:51:13","post_content_filtered":"","post_parent":"12145","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/foto-1123_10536.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"25695"},{"ID":"25697","post_author":"2","post_date":"2025-03-08 11:42:53","post_date_gmt":"2025-03-08 10:42:53","post_content":"","post_title":"foto-1123_10537","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"foto-1123_10537","to_ping":"","pinged":"","post_modified":"2025-04-21 13:51:13","post_modified_gmt":"2025-04-21 11:51:13","post_content_filtered":"","post_parent":"12145","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/foto-1123_10537.jpeg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"25697"},{"ID":"25699","post_author":"2","post_date":"2025-03-08 11:42:55","post_date_gmt":"2025-03-08 10:42:55","post_content":"","post_title":"foto-1123_10538","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"foto-1123_10538","to_ping":"","pinged":"","post_modified":"2025-04-21 13:51:13","post_modified_gmt":"2025-04-21 11:51:13","post_content_filtered":"","post_parent":"12145","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/foto-1123_10538.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"25699"}],"nombrepaginaes":"plaza-del-ayuntamiento","nombrepaginaen":"town-hall-square","latitud_gps":"","longitud_gps":"","adicionaleses":"Para rodajes profesionales: es necesario solicitar permiso para la ocupaci\u00f3n de v\u00eda p\u00fablica a trav\u00e9s de Alicante Film Office. Durante los periodos festivos se realizan diferentes tipos de eventos en este lugar, por lo que es importante consultar las fecha","adicionalesen":"For professional filming: it is necessary to request permission for the occupation of public roads through the Alicante Film Office. During the festive periods, different types of events are held at this location, so it is important to check the available","videoes":"","videoen":"","video2es":"","video2en":"","_links":{"self":[{"href":"https:\/\/spainfilmcommission.com\/en\/wp-json\/wp\/v2\/localizaciones\/localizacion\/12145","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/spainfilmcommission.com\/en\/wp-json\/wp\/v2\/localizaciones\/localizacion"}],"about":[{"href":"https:\/\/spainfilmcommission.com\/en\/wp-json\/wp\/v2\/types\/localizacion"}],"author":[{"embeddable":true,"href":"https:\/\/spainfilmcommission.com\/en\/wp-json\/wp\/v2\/users\/2"}],"wp:attachment":[{"href":"https:\/\/spainfilmcommission.com\/en\/wp-json\/wp\/v2\/media?parent=12145"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}