{"id":12078,"date":"2025-02-27T19:51:46","date_gmt":"2025-02-27T18:51:46","guid":{"rendered":"https:\/\/spainfilmcommission.com\/?post_type=localizacion&#038;p=12078"},"modified":"2025-04-21T18:45:45","modified_gmt":"2025-04-21T16:45:45","slug":"cantera-de-alpedrete","status":"publish","type":"localizacion","link":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/cantera-de-alpedrete\/","title":{"rendered":"Cantera de Alpedrete"},"content":{"rendered":"","protected":false},"author":2,"template":"","meta":[],"class_list":["post-12078","localizacion","type-localizacion","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rodar en Cantera de Alpedrete - Spain Film Commission<\/title>\n<meta name=\"description\" content=\"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Cantera de Alpedrete\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/spainfilmcommission.com\/en\/ai-locations\/cantera-de-alpedrete\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rodar en Cantera de Alpedrete - Spain Film Commission\" \/>\n<meta property=\"og:description\" content=\"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Cantera de Alpedrete\" \/>\n<meta property=\"og:url\" content=\"https:\/\/spainfilmcommission.com\/en\/ai-locations\/cantera-de-alpedrete\/\" \/>\n<meta property=\"og:site_name\" content=\"Spain Film Commission\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-21T16:45:45+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/ai-locations\\\/cantera-de-alpedrete\\\/\",\"url\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/ai-locations\\\/cantera-de-alpedrete\\\/\",\"name\":\"Rodar en Cantera de Alpedrete - Spain Film Commission\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#website\"},\"datePublished\":\"2025-02-27T18:51:46+00:00\",\"dateModified\":\"2025-04-21T16:45:45+00:00\",\"description\":\"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Cantera de Alpedrete\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/ai-locations\\\/cantera-de-alpedrete\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/ai-locations\\\/cantera-de-alpedrete\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/ai-locations\\\/cantera-de-alpedrete\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cantera de Alpedrete\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/\",\"name\":\"Spain Film Commission\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#organization\",\"name\":\"Spain Film Commission\",\"url\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/spainfilmcommission.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/SPC_COLOR.png\",\"contentUrl\":\"https:\\\/\\\/spainfilmcommission.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/SPC_COLOR.png\",\"width\":1665,\"height\":1665,\"caption\":\"Spain Film Commission\"},\"image\":{\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rodar en Cantera de Alpedrete - Spain Film Commission","description":"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Cantera de Alpedrete","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/cantera-de-alpedrete\/","og_locale":"en_US","og_type":"article","og_title":"Rodar en Cantera de Alpedrete - Spain Film Commission","og_description":"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Cantera de Alpedrete","og_url":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/cantera-de-alpedrete\/","og_site_name":"Spain Film Commission","article_modified_time":"2025-04-21T16:45:45+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/cantera-de-alpedrete\/","url":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/cantera-de-alpedrete\/","name":"Rodar en Cantera de Alpedrete - Spain Film Commission","isPartOf":{"@id":"https:\/\/spainfilmcommission.com\/en\/#website"},"datePublished":"2025-02-27T18:51:46+00:00","dateModified":"2025-04-21T16:45:45+00:00","description":"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Cantera de Alpedrete","breadcrumb":{"@id":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/cantera-de-alpedrete\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/spainfilmcommission.com\/en\/ai-locations\/cantera-de-alpedrete\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/cantera-de-alpedrete\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/spainfilmcommission.com\/en\/"},{"@type":"ListItem","position":2,"name":"Cantera de Alpedrete"}]},{"@type":"WebSite","@id":"https:\/\/spainfilmcommission.com\/en\/#website","url":"https:\/\/spainfilmcommission.com\/en\/","name":"Spain Film Commission","description":"","publisher":{"@id":"https:\/\/spainfilmcommission.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/spainfilmcommission.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/spainfilmcommission.com\/en\/#organization","name":"Spain Film Commission","url":"https:\/\/spainfilmcommission.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/spainfilmcommission.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2024\/07\/SPC_COLOR.png","contentUrl":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2024\/07\/SPC_COLOR.png","width":1665,"height":1665,"caption":"Spain Film Commission"},"image":{"@id":"https:\/\/spainfilmcommission.com\/en\/#\/schema\/logo\/image\/"}}]}},"socio":[{"ID":"23","user_login":"film-madrid","user_nicename":"film-madrid","display_name":"film-madrid","user_pass":"****************","user_email":"filmmadrid@madrid.org","user_url":"","user_registered":"2024-12-19 15:35:18","id":23}],"nombrees":"Cantera de Alpedrete","nombreen":"Cantera de Alpedrete","localidad":"Alpedrete","provincia":"Madrid","coordenadas_maps":"40.66106475256127, -4.011038002245931","latitud":"40.661064752561","longitud":"-4.011038002246","direcciones":"","direccionen":"","cod_postal":[],"telefono":"","fax":"","mail":"","web":"","descripciones":"Parque natural situado en la Dehesa El Boyal, dentro del municipio madrile\u00f1o de Alpedrete. Las canteras cuentan con una impresionante laguna que rodea a los acantilados de roca, y por la que circulan diversos riachuelos.","descripcionen":"Natural park located in the Dehesa El Boyal, within the Madrid municipality of Alpedrete. The quarries have an impressive low lagoon that surrounds the rock cliffs, and through which various streams circulate.","galeria":[{"ID":"25389","post_author":"2","post_date":"2025-03-08 04:15:42","post_date_gmt":"2025-03-08 03:15:42","post_content":"","post_title":"foto-1053_9200","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"foto-1053_9200","to_ping":"","pinged":"","post_modified":"2025-04-21 18:45:45","post_modified_gmt":"2025-04-21 16:45:45","post_content_filtered":"","post_parent":"12078","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/foto-1053_9200.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"25389"}],"nombrepaginaes":"cantera-de-alpedrete","nombrepaginaen":"cantera-de-alpedrete","latitud_gps":"40\u00b039'39.7","longitud_gps":"4\u00b000'39.5","adicionaleses":"","adicionalesen":"","videoes":"","videoen":"","video2es":"","video2en":"","_links":{"self":[{"href":"https:\/\/spainfilmcommission.com\/en\/wp-json\/wp\/v2\/localizaciones\/localizacion\/12078","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/spainfilmcommission.com\/en\/wp-json\/wp\/v2\/localizaciones\/localizacion"}],"about":[{"href":"https:\/\/spainfilmcommission.com\/en\/wp-json\/wp\/v2\/types\/localizacion"}],"author":[{"embeddable":true,"href":"https:\/\/spainfilmcommission.com\/en\/wp-json\/wp\/v2\/users\/2"}],"wp:attachment":[{"href":"https:\/\/spainfilmcommission.com\/en\/wp-json\/wp\/v2\/media?parent=12078"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}