{"id":12058,"date":"2025-02-27T19:49:16","date_gmt":"2025-02-27T18:49:16","guid":{"rendered":"https:\/\/spainfilmcommission.com\/?post_type=localizacion&#038;p=12058"},"modified":"2025-04-21T13:29:12","modified_gmt":"2025-04-21T11:29:12","slug":"valencia-de-don-juan","status":"publish","type":"localizacion","link":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/valencia-de-don-juan\/","title":{"rendered":"Valencia de Don Juan"},"content":{"rendered":"","protected":false},"author":2,"template":"","meta":[],"class_list":["post-12058","localizacion","type-localizacion","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rodar en Valencia de Don Juan - Spain Film Commission<\/title>\n<meta name=\"description\" content=\"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Valencia de Don Juan\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/spainfilmcommission.com\/en\/ai-locations\/valencia-de-don-juan\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rodar en Valencia de Don Juan - Spain Film Commission\" \/>\n<meta property=\"og:description\" content=\"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Valencia de Don Juan\" \/>\n<meta property=\"og:url\" content=\"https:\/\/spainfilmcommission.com\/en\/ai-locations\/valencia-de-don-juan\/\" \/>\n<meta property=\"og:site_name\" content=\"Spain Film Commission\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-21T11:29:12+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/ai-locations\\\/valencia-de-don-juan\\\/\",\"url\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/ai-locations\\\/valencia-de-don-juan\\\/\",\"name\":\"Rodar en Valencia de Don Juan - Spain Film Commission\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#website\"},\"datePublished\":\"2025-02-27T18:49:16+00:00\",\"dateModified\":\"2025-04-21T11:29:12+00:00\",\"description\":\"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Valencia de Don Juan\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/ai-locations\\\/valencia-de-don-juan\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/ai-locations\\\/valencia-de-don-juan\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/ai-locations\\\/valencia-de-don-juan\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Valencia de Don Juan\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/\",\"name\":\"Spain Film Commission\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#organization\",\"name\":\"Spain Film Commission\",\"url\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/spainfilmcommission.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/SPC_COLOR.png\",\"contentUrl\":\"https:\\\/\\\/spainfilmcommission.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/SPC_COLOR.png\",\"width\":1665,\"height\":1665,\"caption\":\"Spain Film Commission\"},\"image\":{\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rodar en Valencia de Don Juan - Spain Film Commission","description":"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Valencia de Don Juan","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/valencia-de-don-juan\/","og_locale":"en_US","og_type":"article","og_title":"Rodar en Valencia de Don Juan - Spain Film Commission","og_description":"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Valencia de Don Juan","og_url":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/valencia-de-don-juan\/","og_site_name":"Spain Film Commission","article_modified_time":"2025-04-21T11:29:12+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/valencia-de-don-juan\/","url":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/valencia-de-don-juan\/","name":"Rodar en Valencia de Don Juan - Spain Film Commission","isPartOf":{"@id":"https:\/\/spainfilmcommission.com\/en\/#website"},"datePublished":"2025-02-27T18:49:16+00:00","dateModified":"2025-04-21T11:29:12+00:00","description":"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Valencia de Don Juan","breadcrumb":{"@id":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/valencia-de-don-juan\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/spainfilmcommission.com\/en\/ai-locations\/valencia-de-don-juan\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/valencia-de-don-juan\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/spainfilmcommission.com\/en\/"},{"@type":"ListItem","position":2,"name":"Valencia de Don Juan"}]},{"@type":"WebSite","@id":"https:\/\/spainfilmcommission.com\/en\/#website","url":"https:\/\/spainfilmcommission.com\/en\/","name":"Spain Film Commission","description":"","publisher":{"@id":"https:\/\/spainfilmcommission.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/spainfilmcommission.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/spainfilmcommission.com\/en\/#organization","name":"Spain Film Commission","url":"https:\/\/spainfilmcommission.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/spainfilmcommission.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2024\/07\/SPC_COLOR.png","contentUrl":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2024\/07\/SPC_COLOR.png","width":1665,"height":1665,"caption":"Spain Film Commission"},"image":{"@id":"https:\/\/spainfilmcommission.com\/en\/#\/schema\/logo\/image\/"}}]}},"socio":[{"ID":"28","user_login":"castilla-y-leon-film-commission","user_nicename":"castilla-y-leon-film-commission","display_name":"castilla-y-leon-film-commission","user_pass":"****************","user_email":"kristine.guzman@jcyl.es","user_url":"","user_registered":"2024-12-19 15:53:09","id":28}],"nombrees":"Valencia de Don Juan","nombreen":"Valencia de Don Juan","localidad":"Valencia de Don Juan","provincia":"Le\u00f3n","coordenadas_maps":"42.29361, -5.52089","latitud":"42.293610000000","longitud":"-5.520890000000","direcciones":"","direccionen":"","cod_postal":[],"telefono":"","fax":"","mail":"","web":"","descripciones":"Imponente castillo de arquitectura g\u00f3tico-militar de finales del s. XV, rodeado por un quiosco de m\u00fasica, estanque de patos, fuentes y un auditorio; se presta a todo tipo de rodajes b\u00e9licos e hist\u00f3ricos, como ya hizo el famoso grupo de humor brit\u00e1nico Monty Python. La comarca de Los Oteros, zona seca y soleada de aspecto ondulado con arquitectura tradicional de adobe, con palomares y bodegas y campos de vi\u00f1edos propios de esta zona. Caser\u00edos derruidos, pueblos pr\u00e1cticamente abandonados completan el escenario. Destacan el Molino Los Puentes (molino derruido alrededor de campos de cultivo), casa modernista de la Plaza Eliseo Ortiz, la Plaza de Toros, las piscinas, los antiguos edificios ferroviarios situados en la actual V\u00eda Verde y el Edificio Centinela, digno de una pel\u00edcula de terror. Resaltar la luz de sus atardeceres, que proporciona unos escenarios de car\u00e1cter buc\u00f3lico. La Ribera del Esla y la V\u00eda Verde proporcionan el verdor y la frescura.","descripcionen":"Imposing castle of gothic-military architecture from the end of the s. XV, surrounded by a bandstand, duck pond, fountains and an auditorium; lends itself to all kinds of military and historical filming, as the famous British comedy group Monty Python did. The region of Los Oteros, a dry and sunny area with an undulating aspect with traditional adobe architecture, with dovecotes and wineries and vineyards typical of this area. Ruined farmhouses, practically abandoned villages complete the scene. Highlights include the Molino Los Puentes (a demolished mill around crop fields), the modernist house in Plaza Eliseo Ortiz, the Plaza de Toros, the swimming pools, the old railway buildings located on the current V\u00eda Verde and the Centinela Building, worthy of a horror movie. Highlight the light of its sunsets, which provides scenes of a bucolic nature. The Ribera del Esla and the V\u00eda Verde provide greenery and freshness.","galeria":[{"ID":"25137","post_author":"2","post_date":"2025-03-08 04:10:16","post_date_gmt":"2025-03-08 03:10:16","post_content":"","post_title":"foto-1033_9058","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"foto-1033_9058","to_ping":"","pinged":"","post_modified":"2025-04-21 13:29:12","post_modified_gmt":"2025-04-21 11:29:12","post_content_filtered":"","post_parent":"12058","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/foto-1033_9058.jpeg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"25137"},{"ID":"25139","post_author":"2","post_date":"2025-03-08 04:10:19","post_date_gmt":"2025-03-08 03:10:19","post_content":"","post_title":"foto-1033_9059","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"foto-1033_9059","to_ping":"","pinged":"","post_modified":"2025-04-21 13:29:12","post_modified_gmt":"2025-04-21 11:29:12","post_content_filtered":"","post_parent":"12058","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/foto-1033_9059.jpeg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"25139"},{"ID":"25141","post_author":"2","post_date":"2025-03-08 04:10:21","post_date_gmt":"2025-03-08 03:10:21","post_content":"","post_title":"foto-1033_9060","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"foto-1033_9060","to_ping":"","pinged":"","post_modified":"2025-04-21 13:29:12","post_modified_gmt":"2025-04-21 11:29:12","post_content_filtered":"","post_parent":"12058","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/foto-1033_9060.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"25141"},{"ID":"25143","post_author":"2","post_date":"2025-03-08 04:10:23","post_date_gmt":"2025-03-08 03:10:23","post_content":"","post_title":"foto-1033_9061","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"foto-1033_9061","to_ping":"","pinged":"","post_modified":"2025-04-21 13:29:12","post_modified_gmt":"2025-04-21 11:29:12","post_content_filtered":"","post_parent":"12058","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/foto-1033_9061.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"25143"},{"ID":"25145","post_author":"2","post_date":"2025-03-08 04:10:25","post_date_gmt":"2025-03-08 03:10:25","post_content":"","post_title":"foto-1033_9062","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"foto-1033_9062","to_ping":"","pinged":"","post_modified":"2025-04-21 13:29:12","post_modified_gmt":"2025-04-21 11:29:12","post_content_filtered":"","post_parent":"12058","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/foto-1033_9062.jpeg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"25145"},{"ID":"25147","post_author":"2","post_date":"2025-03-08 04:10:27","post_date_gmt":"2025-03-08 03:10:27","post_content":"","post_title":"foto-1033_9063","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"foto-1033_9063","to_ping":"","pinged":"","post_modified":"2025-04-21 13:29:12","post_modified_gmt":"2025-04-21 11:29:12","post_content_filtered":"","post_parent":"12058","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/foto-1033_9063.jpeg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"25147"},{"ID":"25149","post_author":"2","post_date":"2025-03-08 04:10:29","post_date_gmt":"2025-03-08 03:10:29","post_content":"","post_title":"foto-1033_9064","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"foto-1033_9064","to_ping":"","pinged":"","post_modified":"2025-04-21 13:29:12","post_modified_gmt":"2025-04-21 11:29:12","post_content_filtered":"","post_parent":"12058","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/foto-1033_9064.jpeg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"25149"},{"ID":"25151","post_author":"2","post_date":"2025-03-08 04:10:31","post_date_gmt":"2025-03-08 03:10:31","post_content":"","post_title":"foto-1033_9065","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"foto-1033_9065","to_ping":"","pinged":"","post_modified":"2025-04-21 13:29:12","post_modified_gmt":"2025-04-21 11:29:12","post_content_filtered":"","post_parent":"12058","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/foto-1033_9065.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"25151"},{"ID":"25153","post_author":"2","post_date":"2025-03-08 04:10:33","post_date_gmt":"2025-03-08 03:10:33","post_content":"","post_title":"foto-1033_9066","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"foto-1033_9066","to_ping":"","pinged":"","post_modified":"2025-04-21 13:29:12","post_modified_gmt":"2025-04-21 11:29:12","post_content_filtered":"","post_parent":"12058","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/foto-1033_9066.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"25153"},{"ID":"25155","post_author":"2","post_date":"2025-03-08 04:10:35","post_date_gmt":"2025-03-08 03:10:35","post_content":"","post_title":"foto-1033_9067","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"foto-1033_9067","to_ping":"","pinged":"","post_modified":"2025-04-21 13:29:12","post_modified_gmt":"2025-04-21 11:29:12","post_content_filtered":"","post_parent":"12058","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/foto-1033_9067.jpeg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"25155"},{"ID":"25157","post_author":"2","post_date":"2025-03-08 04:10:37","post_date_gmt":"2025-03-08 03:10:37","post_content":"","post_title":"foto-1033_9068","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"foto-1033_9068","to_ping":"","pinged":"","post_modified":"2025-04-21 13:29:12","post_modified_gmt":"2025-04-21 11:29:12","post_content_filtered":"","post_parent":"12058","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/foto-1033_9068.jpeg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"25157"},{"ID":"25159","post_author":"2","post_date":"2025-03-08 04:10:40","post_date_gmt":"2025-03-08 03:10:40","post_content":"","post_title":"foto-1033_9069","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"foto-1033_9069","to_ping":"","pinged":"","post_modified":"2025-04-21 13:29:12","post_modified_gmt":"2025-04-21 11:29:12","post_content_filtered":"","post_parent":"12058","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/foto-1033_9069.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"25159"},{"ID":"25161","post_author":"2","post_date":"2025-03-08 04:10:42","post_date_gmt":"2025-03-08 03:10:42","post_content":"","post_title":"foto-1033_9070","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"foto-1033_9070","to_ping":"","pinged":"","post_modified":"2025-04-21 13:29:12","post_modified_gmt":"2025-04-21 11:29:12","post_content_filtered":"","post_parent":"12058","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/foto-1033_9070.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"25161"}],"nombrepaginaes":"valencia-de-don-juan","nombrepaginaen":"valencia-de-don-juan","latitud_gps":"42\u00b017'37.2","longitud_gps":"5\u00b031'15.5","adicionaleses":"","adicionalesen":"","videoes":"","videoen":"","video2es":"","video2en":"","_links":{"self":[{"href":"https:\/\/spainfilmcommission.com\/en\/wp-json\/wp\/v2\/localizaciones\/localizacion\/12058","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/spainfilmcommission.com\/en\/wp-json\/wp\/v2\/localizaciones\/localizacion"}],"about":[{"href":"https:\/\/spainfilmcommission.com\/en\/wp-json\/wp\/v2\/types\/localizacion"}],"author":[{"embeddable":true,"href":"https:\/\/spainfilmcommission.com\/en\/wp-json\/wp\/v2\/users\/2"}],"wp:attachment":[{"href":"https:\/\/spainfilmcommission.com\/en\/wp-json\/wp\/v2\/media?parent=12058"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}