{"id":12011,"date":"2025-02-27T19:49:16","date_gmt":"2025-02-27T18:49:16","guid":{"rendered":"https:\/\/spainfilmcommission.com\/?post_type=localizacion&#038;p=12011"},"modified":"2025-04-22T08:35:45","modified_gmt":"2025-04-22T06:35:45","slug":"cuevas-de-navarra","status":"publish","type":"localizacion","link":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/cuevas-de-navarra\/","title":{"rendered":"Cuevas de Navarra"},"content":{"rendered":"","protected":false},"author":2,"template":"","meta":[],"class_list":["post-12011","localizacion","type-localizacion","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rodar en Cuevas de Navarra - Spain Film Commission<\/title>\n<meta name=\"description\" content=\"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Cuevas de Navarra\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/spainfilmcommission.com\/en\/ai-locations\/cuevas-de-navarra\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rodar en Cuevas de Navarra - Spain Film Commission\" \/>\n<meta property=\"og:description\" content=\"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Cuevas de Navarra\" \/>\n<meta property=\"og:url\" content=\"https:\/\/spainfilmcommission.com\/en\/ai-locations\/cuevas-de-navarra\/\" \/>\n<meta property=\"og:site_name\" content=\"Spain Film Commission\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-22T06:35:45+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/ai-locations\\\/cuevas-de-navarra\\\/\",\"url\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/ai-locations\\\/cuevas-de-navarra\\\/\",\"name\":\"Rodar en Cuevas de Navarra - Spain Film Commission\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#website\"},\"datePublished\":\"2025-02-27T18:49:16+00:00\",\"dateModified\":\"2025-04-22T06:35:45+00:00\",\"description\":\"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Cuevas de Navarra\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/ai-locations\\\/cuevas-de-navarra\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/ai-locations\\\/cuevas-de-navarra\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/ai-locations\\\/cuevas-de-navarra\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cuevas de Navarra\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/\",\"name\":\"Spain Film Commission\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#organization\",\"name\":\"Spain Film Commission\",\"url\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/spainfilmcommission.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/SPC_COLOR.png\",\"contentUrl\":\"https:\\\/\\\/spainfilmcommission.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/SPC_COLOR.png\",\"width\":1665,\"height\":1665,\"caption\":\"Spain Film Commission\"},\"image\":{\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rodar en Cuevas de Navarra - Spain Film Commission","description":"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Cuevas de Navarra","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/cuevas-de-navarra\/","og_locale":"en_US","og_type":"article","og_title":"Rodar en Cuevas de Navarra - Spain Film Commission","og_description":"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Cuevas de Navarra","og_url":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/cuevas-de-navarra\/","og_site_name":"Spain Film Commission","article_modified_time":"2025-04-22T06:35:45+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/cuevas-de-navarra\/","url":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/cuevas-de-navarra\/","name":"Rodar en Cuevas de Navarra - Spain Film Commission","isPartOf":{"@id":"https:\/\/spainfilmcommission.com\/en\/#website"},"datePublished":"2025-02-27T18:49:16+00:00","dateModified":"2025-04-22T06:35:45+00:00","description":"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Cuevas de Navarra","breadcrumb":{"@id":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/cuevas-de-navarra\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/spainfilmcommission.com\/en\/ai-locations\/cuevas-de-navarra\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/cuevas-de-navarra\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/spainfilmcommission.com\/en\/"},{"@type":"ListItem","position":2,"name":"Cuevas de Navarra"}]},{"@type":"WebSite","@id":"https:\/\/spainfilmcommission.com\/en\/#website","url":"https:\/\/spainfilmcommission.com\/en\/","name":"Spain Film Commission","description":"","publisher":{"@id":"https:\/\/spainfilmcommission.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/spainfilmcommission.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/spainfilmcommission.com\/en\/#organization","name":"Spain Film Commission","url":"https:\/\/spainfilmcommission.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/spainfilmcommission.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2024\/07\/SPC_COLOR.png","contentUrl":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2024\/07\/SPC_COLOR.png","width":1665,"height":1665,"caption":"Spain Film Commission"},"image":{"@id":"https:\/\/spainfilmcommission.com\/en\/#\/schema\/logo\/image\/"}}]}},"socio":[{"ID":"43","user_login":"navarra-film-commission","user_nicename":"navarra-film-commission","display_name":"Navarra Film Commission","user_pass":"****************","user_email":"s.sevilla@nicdo.es","user_url":"","user_registered":"2024-12-19 17:48:02","id":43}],"nombrees":"Cuevas de Navarra","nombreen":"Caves of Navarre","localidad":"Varios","provincia":"Navarra","coordenadas_maps":"43.276451, -1.512651","latitud":"43.276451000000","longitud":"-1.512651000000","direcciones":"","direccionen":"","cod_postal":[],"telefono":"","fax":"","mail":"","web":"","descripciones":"La de Zugarramurdi es la m\u00e1s famosa de ellas, pero en Navarra hay m\u00e1s cuevas acondicionadas en las que podemos adentrarnos.\u00a0 En el valle de Larraun, en el concejo de Astitz, a pocos minutos de Lekunberri, surge la cueva de Mendukilo que revela las profundidades de la Sierra de Aralar. Sus \u00edntimos secretos reservados a espeol\u00f3logos durante a\u00f1os, son ya accesibles al p\u00fablico en general gracias a los trabajos de acondicionamiento llevados a cabo.\u00a0 En la peque\u00f1a localidad pirenaica de Urdazubi\/Urdax encontramos la cueva de Ikaburu. Se trata de una gruta que se origin\u00f3 hace unos 14.000 a\u00f1os gracias a la continua erosi\u00f3n del r\u00edo Urtxuma. Una visita guiada por sus galer\u00edas -\u00fanica forma de conocerla- te adentrar\u00e1 en un m\u00e1gico universo de estalactitas y estalagmitas, adem\u00e1s de traerte evocadores recuerdos de personajes de leyenda, guerrilleros y contrabandistas que las ocuparon en otras \u00e9pocas.","descripcionen":"Zugarramurdi is the most famous, but Navarre has several caves we can explore.\u00a0 In the Larraun valley, in the municipality of Astitz, a few minutes from Lekunberri, you will find the cave of Mendukilo, which reveals the depths of the Aralar mountain range. Its secrets, reserved for speleologists for years, are now open to the general public thanks to the work done to make it accessible. In the small Pyrenean village of Urdazubi\/Urdax we can find the Ikaburu cave. It is a a grotto that originated some 14,000 years ago as a result of the erosion of the river Urtxuma that runs through it. A guided tour through its galleries- the only way to visit it - will open up a whole universe of stalactites and stalagmites as well as evoking the memories of people of legend: the soldiers and smugglers who used to occupy the caves in earlier times.","galeria":[{"ID":"23841","post_author":"2","post_date":"2025-03-08 03:46:43","post_date_gmt":"2025-03-08 02:46:43","post_content":"","post_title":"foto-986_8224","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"foto-986_8224","to_ping":"","pinged":"","post_modified":"2025-04-22 08:35:45","post_modified_gmt":"2025-04-22 06:35:45","post_content_filtered":"","post_parent":"12011","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/foto-986_8224.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"23841"},{"ID":"23843","post_author":"2","post_date":"2025-03-08 03:46:45","post_date_gmt":"2025-03-08 02:46:45","post_content":"","post_title":"foto-986_8225","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"foto-986_8225","to_ping":"","pinged":"","post_modified":"2025-04-22 08:35:45","post_modified_gmt":"2025-04-22 06:35:45","post_content_filtered":"","post_parent":"12011","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/foto-986_8225.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"23843"},{"ID":"23845","post_author":"2","post_date":"2025-03-08 03:46:47","post_date_gmt":"2025-03-08 02:46:47","post_content":"","post_title":"foto-986_8226","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"foto-986_8226","to_ping":"","pinged":"","post_modified":"2025-04-22 08:35:45","post_modified_gmt":"2025-04-22 06:35:45","post_content_filtered":"","post_parent":"12011","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/foto-986_8226.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"23845"},{"ID":"23847","post_author":"2","post_date":"2025-03-08 03:46:50","post_date_gmt":"2025-03-08 02:46:50","post_content":"","post_title":"foto-986_8227","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"foto-986_8227","to_ping":"","pinged":"","post_modified":"2025-04-22 08:35:45","post_modified_gmt":"2025-04-22 06:35:45","post_content_filtered":"","post_parent":"12011","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/foto-986_8227.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"23847"},{"ID":"23849","post_author":"2","post_date":"2025-03-08 03:46:52","post_date_gmt":"2025-03-08 02:46:52","post_content":"","post_title":"foto-986_8228","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"foto-986_8228","to_ping":"","pinged":"","post_modified":"2025-04-22 08:35:45","post_modified_gmt":"2025-04-22 06:35:45","post_content_filtered":"","post_parent":"12011","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/foto-986_8228.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"23849"}],"nombrepaginaes":"cuevas-de-navarra","nombrepaginaen":"caves-of-navarre","latitud_gps":"43\u00b016'35.2\"N","longitud_gps":"1\u00b030'45.5\"W","adicionaleses":"","adicionalesen":"","videoes":"https:\/\/www.youtube.com\/watch?v=UIXA7sH1rNA","videoen":"","video2es":"https:\/\/www.youtube.com\/watch?v=2Tt0UnP3rnc","video2en":"","_links":{"self":[{"href":"https:\/\/spainfilmcommission.com\/en\/wp-json\/wp\/v2\/localizaciones\/localizacion\/12011","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/spainfilmcommission.com\/en\/wp-json\/wp\/v2\/localizaciones\/localizacion"}],"about":[{"href":"https:\/\/spainfilmcommission.com\/en\/wp-json\/wp\/v2\/types\/localizacion"}],"author":[{"embeddable":true,"href":"https:\/\/spainfilmcommission.com\/en\/wp-json\/wp\/v2\/users\/2"}],"wp:attachment":[{"href":"https:\/\/spainfilmcommission.com\/en\/wp-json\/wp\/v2\/media?parent=12011"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}