{"id":11965,"date":"2025-02-27T19:49:16","date_gmt":"2025-02-27T18:49:16","guid":{"rendered":"https:\/\/spainfilmcommission.com\/?post_type=localizacion&#038;p=11965"},"modified":"2025-04-21T19:11:45","modified_gmt":"2025-04-21T17:11:45","slug":"casa-palacio-de-los-briones","status":"publish","type":"localizacion","link":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/casa-palacio-de-los-briones\/","title":{"rendered":"Casa Palacio de los Briones"},"content":{"rendered":"","protected":false},"author":2,"template":"","meta":[],"class_list":["post-11965","localizacion","type-localizacion","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rodar en Casa Palacio de los Briones - Spain Film Commission<\/title>\n<meta name=\"description\" content=\"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Casa Palacio de los Briones\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/spainfilmcommission.com\/en\/ai-locations\/casa-palacio-de-los-briones\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rodar en Casa Palacio de los Briones - Spain Film Commission\" \/>\n<meta property=\"og:description\" content=\"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Casa Palacio de los Briones\" \/>\n<meta property=\"og:url\" content=\"https:\/\/spainfilmcommission.com\/en\/ai-locations\/casa-palacio-de-los-briones\/\" \/>\n<meta property=\"og:site_name\" content=\"Spain Film Commission\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-21T17:11:45+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/ai-locations\\\/casa-palacio-de-los-briones\\\/\",\"url\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/ai-locations\\\/casa-palacio-de-los-briones\\\/\",\"name\":\"Rodar en Casa Palacio de los Briones - Spain Film Commission\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#website\"},\"datePublished\":\"2025-02-27T18:49:16+00:00\",\"dateModified\":\"2025-04-21T17:11:45+00:00\",\"description\":\"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Casa Palacio de los Briones\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/ai-locations\\\/casa-palacio-de-los-briones\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/ai-locations\\\/casa-palacio-de-los-briones\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/ai-locations\\\/casa-palacio-de-los-briones\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Casa Palacio de los Briones\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/\",\"name\":\"Spain Film Commission\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#organization\",\"name\":\"Spain Film Commission\",\"url\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/spainfilmcommission.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/SPC_COLOR.png\",\"contentUrl\":\"https:\\\/\\\/spainfilmcommission.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/SPC_COLOR.png\",\"width\":1665,\"height\":1665,\"caption\":\"Spain Film Commission\"},\"image\":{\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rodar en Casa Palacio de los Briones - Spain Film Commission","description":"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Casa Palacio de los Briones","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/casa-palacio-de-los-briones\/","og_locale":"en_US","og_type":"article","og_title":"Rodar en Casa Palacio de los Briones - Spain Film Commission","og_description":"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Casa Palacio de los Briones","og_url":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/casa-palacio-de-los-briones\/","og_site_name":"Spain Film Commission","article_modified_time":"2025-04-21T17:11:45+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/casa-palacio-de-los-briones\/","url":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/casa-palacio-de-los-briones\/","name":"Rodar en Casa Palacio de los Briones - Spain Film Commission","isPartOf":{"@id":"https:\/\/spainfilmcommission.com\/en\/#website"},"datePublished":"2025-02-27T18:49:16+00:00","dateModified":"2025-04-21T17:11:45+00:00","description":"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Casa Palacio de los Briones","breadcrumb":{"@id":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/casa-palacio-de-los-briones\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/spainfilmcommission.com\/en\/ai-locations\/casa-palacio-de-los-briones\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/casa-palacio-de-los-briones\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/spainfilmcommission.com\/en\/"},{"@type":"ListItem","position":2,"name":"Casa Palacio de los Briones"}]},{"@type":"WebSite","@id":"https:\/\/spainfilmcommission.com\/en\/#website","url":"https:\/\/spainfilmcommission.com\/en\/","name":"Spain Film Commission","description":"","publisher":{"@id":"https:\/\/spainfilmcommission.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/spainfilmcommission.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/spainfilmcommission.com\/en\/#organization","name":"Spain Film Commission","url":"https:\/\/spainfilmcommission.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/spainfilmcommission.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2024\/07\/SPC_COLOR.png","contentUrl":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2024\/07\/SPC_COLOR.png","width":1665,"height":1665,"caption":"Spain Film Commission"},"image":{"@id":"https:\/\/spainfilmcommission.com\/en\/#\/schema\/logo\/image\/"}}]}},"socio":[{"ID":"38","user_login":"carmona-film-office","user_nicename":"carmona-film-office","display_name":"carmona-film-office","user_pass":"****************","user_email":"pmoreno@carmona.org","user_url":"","user_registered":"2024-12-19 16:40:55","id":38}],"nombrees":"Casa Palacio de los Briones","nombreen":"Briones\u00b4s Palace","localidad":"CARMONA","provincia":"Sevilla","coordenadas_maps":"37.472958, -5.635888","latitud":"37.472958000000","longitud":"-5.635888000000","direcciones":"","direccionen":"","cod_postal":[],"telefono":"","fax":"","mail":"","web":"http:\/\/upo.es\/","descripciones":"","descripcionen":"","galeria":false,"nombrepaginaes":"casa-palacio-de-los-briones","nombrepaginaen":"brioness-palace","latitud_gps":"37\u00b028'22.7\"N","longitud_gps":"5\u00b038'09.2\"W","adicionaleses":"","adicionalesen":"","videoes":"","videoen":"","video2es":"","video2en":"","_links":{"self":[{"href":"https:\/\/spainfilmcommission.com\/en\/wp-json\/wp\/v2\/localizaciones\/localizacion\/11965","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/spainfilmcommission.com\/en\/wp-json\/wp\/v2\/localizaciones\/localizacion"}],"about":[{"href":"https:\/\/spainfilmcommission.com\/en\/wp-json\/wp\/v2\/types\/localizacion"}],"author":[{"embeddable":true,"href":"https:\/\/spainfilmcommission.com\/en\/wp-json\/wp\/v2\/users\/2"}],"wp:attachment":[{"href":"https:\/\/spainfilmcommission.com\/en\/wp-json\/wp\/v2\/media?parent=11965"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}