{"id":11931,"date":"2025-02-27T19:49:16","date_gmt":"2025-02-27T18:49:16","guid":{"rendered":"https:\/\/spainfilmcommission.com\/?post_type=localizacion&#038;p=11931"},"modified":"2025-04-21T11:56:10","modified_gmt":"2025-04-21T09:56:10","slug":"pueblos-medievales","status":"publish","type":"localizacion","link":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/pueblos-medievales\/","title":{"rendered":"Pueblos Medievales"},"content":{"rendered":"","protected":false},"author":2,"template":"","meta":[],"class_list":["post-11931","localizacion","type-localizacion","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rodar en Pueblos Medievales - Spain Film Commission<\/title>\n<meta name=\"description\" content=\"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Pueblos Medievales\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/spainfilmcommission.com\/en\/ai-locations\/pueblos-medievales\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rodar en Pueblos Medievales - Spain Film Commission\" \/>\n<meta property=\"og:description\" content=\"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Pueblos Medievales\" \/>\n<meta property=\"og:url\" content=\"https:\/\/spainfilmcommission.com\/en\/ai-locations\/pueblos-medievales\/\" \/>\n<meta property=\"og:site_name\" content=\"Spain Film Commission\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-21T09:56:10+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/ai-locations\\\/pueblos-medievales\\\/\",\"url\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/ai-locations\\\/pueblos-medievales\\\/\",\"name\":\"Rodar en Pueblos Medievales - Spain Film Commission\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#website\"},\"datePublished\":\"2025-02-27T18:49:16+00:00\",\"dateModified\":\"2025-04-21T09:56:10+00:00\",\"description\":\"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Pueblos Medievales\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/ai-locations\\\/pueblos-medievales\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/ai-locations\\\/pueblos-medievales\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/ai-locations\\\/pueblos-medievales\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pueblos Medievales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/\",\"name\":\"Spain Film Commission\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#organization\",\"name\":\"Spain Film Commission\",\"url\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/spainfilmcommission.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/SPC_COLOR.png\",\"contentUrl\":\"https:\\\/\\\/spainfilmcommission.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/SPC_COLOR.png\",\"width\":1665,\"height\":1665,\"caption\":\"Spain Film Commission\"},\"image\":{\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rodar en Pueblos Medievales - Spain Film Commission","description":"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Pueblos Medievales","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/pueblos-medievales\/","og_locale":"en_US","og_type":"article","og_title":"Rodar en Pueblos Medievales - Spain Film Commission","og_description":"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Pueblos Medievales","og_url":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/pueblos-medievales\/","og_site_name":"Spain Film Commission","article_modified_time":"2025-04-21T09:56:10+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/pueblos-medievales\/","url":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/pueblos-medievales\/","name":"Rodar en Pueblos Medievales - Spain Film Commission","isPartOf":{"@id":"https:\/\/spainfilmcommission.com\/en\/#website"},"datePublished":"2025-02-27T18:49:16+00:00","dateModified":"2025-04-21T09:56:10+00:00","description":"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Pueblos Medievales","breadcrumb":{"@id":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/pueblos-medievales\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/spainfilmcommission.com\/en\/ai-locations\/pueblos-medievales\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/pueblos-medievales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/spainfilmcommission.com\/en\/"},{"@type":"ListItem","position":2,"name":"Pueblos Medievales"}]},{"@type":"WebSite","@id":"https:\/\/spainfilmcommission.com\/en\/#website","url":"https:\/\/spainfilmcommission.com\/en\/","name":"Spain Film Commission","description":"","publisher":{"@id":"https:\/\/spainfilmcommission.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/spainfilmcommission.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/spainfilmcommission.com\/en\/#organization","name":"Spain Film Commission","url":"https:\/\/spainfilmcommission.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/spainfilmcommission.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2024\/07\/SPC_COLOR.png","contentUrl":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2024\/07\/SPC_COLOR.png","width":1665,"height":1665,"caption":"Spain Film Commission"},"image":{"@id":"https:\/\/spainfilmcommission.com\/en\/#\/schema\/logo\/image\/"}}]}},"socio":[{"ID":"11","user_login":"vitoria-gasteiz-film-office","user_nicename":"vitoria-gasteiz-film-office","display_name":"vitoria-gasteiz-film-office","user_pass":"****************","user_email":"filmoffice@vitoria-gasteiz.org","user_url":"","user_registered":"2024-12-19 13:09:52","id":11}],"nombrees":"Pueblos Medievales","nombreen":"Medieval Towns","localidad":"Anto\u00f1ana","provincia":"\u00c1lava","coordenadas_maps":"42.691396, -2.389695","latitud":"42.691396000000","longitud":"-2.389695000000","direcciones":"","direccionen":"","cod_postal":[],"telefono":"","fax":"","mail":"","web":"","descripciones":"La Provincia de \u00c1lava cuenta con innumerables rincones y pueblos que a\u00fan guardan y mantienen su patrimonio hist\u00f3rico y cultural intacto.","descripcionen":"The Province of Alava has countless corners and villages that still keep and maintain their historical and cultural heritage intact.","galeria":[{"ID":"22939","post_author":"2","post_date":"2025-03-08 03:28:32","post_date_gmt":"2025-03-08 02:28:32","post_content":"","post_title":"foto-903_7717","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"foto-903_7717","to_ping":"","pinged":"","post_modified":"2025-04-21 11:56:10","post_modified_gmt":"2025-04-21 09:56:10","post_content_filtered":"","post_parent":"11931","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/foto-903_7717.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"22939"},{"ID":"22941","post_author":"2","post_date":"2025-03-08 03:28:35","post_date_gmt":"2025-03-08 02:28:35","post_content":"","post_title":"foto-903_7718","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"foto-903_7718","to_ping":"","pinged":"","post_modified":"2025-04-21 11:56:10","post_modified_gmt":"2025-04-21 09:56:10","post_content_filtered":"","post_parent":"11931","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/foto-903_7718.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"22941"},{"ID":"22943","post_author":"2","post_date":"2025-03-08 03:28:36","post_date_gmt":"2025-03-08 02:28:36","post_content":"","post_title":"foto-903_7719","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"foto-903_7719","to_ping":"","pinged":"","post_modified":"2025-04-21 11:56:10","post_modified_gmt":"2025-04-21 09:56:10","post_content_filtered":"","post_parent":"11931","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/foto-903_7719.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"22943"}],"nombrepaginaes":"pueblos-medievales","nombrepaginaen":"medieval-towns","latitud_gps":"42\u00b041'29.0","longitud_gps":"2\u00b023'22.9","adicionaleses":"","adicionalesen":"","videoes":"","videoen":"","video2es":"","video2en":"","_links":{"self":[{"href":"https:\/\/spainfilmcommission.com\/en\/wp-json\/wp\/v2\/localizaciones\/localizacion\/11931","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/spainfilmcommission.com\/en\/wp-json\/wp\/v2\/localizaciones\/localizacion"}],"about":[{"href":"https:\/\/spainfilmcommission.com\/en\/wp-json\/wp\/v2\/types\/localizacion"}],"author":[{"embeddable":true,"href":"https:\/\/spainfilmcommission.com\/en\/wp-json\/wp\/v2\/users\/2"}],"wp:attachment":[{"href":"https:\/\/spainfilmcommission.com\/en\/wp-json\/wp\/v2\/media?parent=11931"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}