{"id":11923,"date":"2025-02-27T19:49:16","date_gmt":"2025-02-27T18:49:16","guid":{"rendered":"https:\/\/spainfilmcommission.com\/?post_type=localizacion&#038;p=11923"},"modified":"2025-04-21T19:46:42","modified_gmt":"2025-04-21T17:46:42","slug":"castillo-de-cortegana","status":"publish","type":"localizacion","link":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/castillo-de-cortegana\/","title":{"rendered":"Castillo de Cortegana"},"content":{"rendered":"","protected":false},"author":2,"template":"","meta":[],"class_list":["post-11923","localizacion","type-localizacion","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rodar en Castillo de Cortegana - Spain Film Commission<\/title>\n<meta name=\"description\" content=\"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Castillo de Cortegana\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/spainfilmcommission.com\/en\/ai-locations\/castillo-de-cortegana\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rodar en Castillo de Cortegana - Spain Film Commission\" \/>\n<meta property=\"og:description\" content=\"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Castillo de Cortegana\" \/>\n<meta property=\"og:url\" content=\"https:\/\/spainfilmcommission.com\/en\/ai-locations\/castillo-de-cortegana\/\" \/>\n<meta property=\"og:site_name\" content=\"Spain Film Commission\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-21T17:46:42+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/ai-locations\\\/castillo-de-cortegana\\\/\",\"url\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/ai-locations\\\/castillo-de-cortegana\\\/\",\"name\":\"Rodar en Castillo de Cortegana - Spain Film Commission\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#website\"},\"datePublished\":\"2025-02-27T18:49:16+00:00\",\"dateModified\":\"2025-04-21T17:46:42+00:00\",\"description\":\"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Castillo de Cortegana\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/ai-locations\\\/castillo-de-cortegana\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/ai-locations\\\/castillo-de-cortegana\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/ai-locations\\\/castillo-de-cortegana\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Castillo de Cortegana\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/\",\"name\":\"Spain Film Commission\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#organization\",\"name\":\"Spain Film Commission\",\"url\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/spainfilmcommission.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/SPC_COLOR.png\",\"contentUrl\":\"https:\\\/\\\/spainfilmcommission.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/SPC_COLOR.png\",\"width\":1665,\"height\":1665,\"caption\":\"Spain Film Commission\"},\"image\":{\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rodar en Castillo de Cortegana - Spain Film Commission","description":"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Castillo de Cortegana","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/castillo-de-cortegana\/","og_locale":"en_US","og_type":"article","og_title":"Rodar en Castillo de Cortegana - Spain Film Commission","og_description":"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Castillo de Cortegana","og_url":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/castillo-de-cortegana\/","og_site_name":"Spain Film Commission","article_modified_time":"2025-04-21T17:46:42+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/castillo-de-cortegana\/","url":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/castillo-de-cortegana\/","name":"Rodar en Castillo de Cortegana - Spain Film Commission","isPartOf":{"@id":"https:\/\/spainfilmcommission.com\/en\/#website"},"datePublished":"2025-02-27T18:49:16+00:00","dateModified":"2025-04-21T17:46:42+00:00","description":"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Castillo de Cortegana","breadcrumb":{"@id":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/castillo-de-cortegana\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/spainfilmcommission.com\/en\/ai-locations\/castillo-de-cortegana\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/castillo-de-cortegana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/spainfilmcommission.com\/en\/"},{"@type":"ListItem","position":2,"name":"Castillo de Cortegana"}]},{"@type":"WebSite","@id":"https:\/\/spainfilmcommission.com\/en\/#website","url":"https:\/\/spainfilmcommission.com\/en\/","name":"Spain Film Commission","description":"","publisher":{"@id":"https:\/\/spainfilmcommission.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/spainfilmcommission.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/spainfilmcommission.com\/en\/#organization","name":"Spain Film Commission","url":"https:\/\/spainfilmcommission.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/spainfilmcommission.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2024\/07\/SPC_COLOR.png","contentUrl":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2024\/07\/SPC_COLOR.png","width":1665,"height":1665,"caption":"Spain Film Commission"},"image":{"@id":"https:\/\/spainfilmcommission.com\/en\/#\/schema\/logo\/image\/"}}]}},"socio":[{"ID":"10","user_login":"andalucia-film-commission","user_nicename":"andalucia-film-commission","display_name":"andalucia-film-commission","user_pass":"****************","user_email":"info@andaluciafilm.com","user_url":"","user_registered":"2024-12-19 07:26:16","id":10}],"nombrees":"Castillo de Cortegana","nombreen":"Cortegana's Castle","localidad":"Cortegana","provincia":"Huelva","coordenadas_maps":"37.910460, -6.816821","latitud":"37.910460000000","longitud":"-6.816821000000","direcciones":"","direccionen":"","cod_postal":[],"telefono":"","fax":"","mail":"","web":"","descripciones":"El castillo de Cortegana es una fortaleza medieval. Construido sobre una peque\u00f1a loma, alrededor de sus m\u00e1s de cuarenta metros dispone de cinco torres, cuatro rectangulares y una m\u00e1s peque\u00f1a circular.","descripcionen":"The castle of Cortegana is a medieval fortress. Built on a small hill, inside its forty meters it has five towers, four of them rectangular and a smaller circular one.","galeria":[{"ID":"22715","post_author":"2","post_date":"2025-03-08 03:24:50","post_date_gmt":"2025-03-08 02:24:50","post_content":"","post_title":"foto-895_7580","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"foto-895_7580","to_ping":"","pinged":"","post_modified":"2025-04-21 19:46:42","post_modified_gmt":"2025-04-21 17:46:42","post_content_filtered":"","post_parent":"11923","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/foto-895_7580.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"22715"},{"ID":"22717","post_author":"2","post_date":"2025-03-08 03:24:54","post_date_gmt":"2025-03-08 02:24:54","post_content":"","post_title":"foto-895_7581","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"foto-895_7581","to_ping":"","pinged":"","post_modified":"2025-04-21 19:46:42","post_modified_gmt":"2025-04-21 17:46:42","post_content_filtered":"","post_parent":"11923","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/foto-895_7581.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"22717"},{"ID":"22719","post_author":"2","post_date":"2025-03-08 03:24:56","post_date_gmt":"2025-03-08 02:24:56","post_content":"","post_title":"foto-895_7582","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"foto-895_7582","to_ping":"","pinged":"","post_modified":"2025-04-21 19:46:42","post_modified_gmt":"2025-04-21 17:46:42","post_content_filtered":"","post_parent":"11923","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/foto-895_7582.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"22719"},{"ID":"22721","post_author":"2","post_date":"2025-03-08 03:24:59","post_date_gmt":"2025-03-08 02:24:59","post_content":"","post_title":"foto-895_7583","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"foto-895_7583","to_ping":"","pinged":"","post_modified":"2025-04-21 19:46:42","post_modified_gmt":"2025-04-21 17:46:42","post_content_filtered":"","post_parent":"11923","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/foto-895_7583.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"22721"},{"ID":"22723","post_author":"2","post_date":"2025-03-08 03:25:02","post_date_gmt":"2025-03-08 02:25:02","post_content":"","post_title":"foto-895_7584","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"foto-895_7584","to_ping":"","pinged":"","post_modified":"2025-04-21 19:46:42","post_modified_gmt":"2025-04-21 17:46:42","post_content_filtered":"","post_parent":"11923","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/foto-895_7584.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"22723"},{"ID":"22725","post_author":"2","post_date":"2025-03-08 03:25:04","post_date_gmt":"2025-03-08 02:25:04","post_content":"","post_title":"foto-895_7585","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"foto-895_7585","to_ping":"","pinged":"","post_modified":"2025-04-21 19:46:42","post_modified_gmt":"2025-04-21 17:46:42","post_content_filtered":"","post_parent":"11923","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/foto-895_7585.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"22725"}],"nombrepaginaes":"castillo-de-cortegana","nombrepaginaen":"corteganas-castle","latitud_gps":"37\u00b054'37.7\"","longitud_gps":"6\u00b049'00.6\"","adicionaleses":"","adicionalesen":"","videoes":"","videoen":"","video2es":"","video2en":"","_links":{"self":[{"href":"https:\/\/spainfilmcommission.com\/en\/wp-json\/wp\/v2\/localizaciones\/localizacion\/11923","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/spainfilmcommission.com\/en\/wp-json\/wp\/v2\/localizaciones\/localizacion"}],"about":[{"href":"https:\/\/spainfilmcommission.com\/en\/wp-json\/wp\/v2\/types\/localizacion"}],"author":[{"embeddable":true,"href":"https:\/\/spainfilmcommission.com\/en\/wp-json\/wp\/v2\/users\/2"}],"wp:attachment":[{"href":"https:\/\/spainfilmcommission.com\/en\/wp-json\/wp\/v2\/media?parent=11923"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}