{"id":11808,"date":"2025-02-27T19:47:41","date_gmt":"2025-02-27T18:47:41","guid":{"rendered":"https:\/\/spainfilmcommission.com\/?post_type=localizacion&#038;p=11808"},"modified":"2025-04-21T18:51:52","modified_gmt":"2025-04-21T16:51:52","slug":"carreteras-1","status":"publish","type":"localizacion","link":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/carreteras-1\/","title":{"rendered":"Carreteras"},"content":{"rendered":"","protected":false},"author":2,"template":"","meta":[],"class_list":["post-11808","localizacion","type-localizacion","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rodar en Carreteras - Spain Film Commission<\/title>\n<meta name=\"description\" content=\"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Carreteras\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/spainfilmcommission.com\/en\/ai-locations\/carreteras-1\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rodar en Carreteras - Spain Film Commission\" \/>\n<meta property=\"og:description\" content=\"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Carreteras\" \/>\n<meta property=\"og:url\" content=\"https:\/\/spainfilmcommission.com\/en\/ai-locations\/carreteras-1\/\" \/>\n<meta property=\"og:site_name\" content=\"Spain Film Commission\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-21T16:51:52+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/ai-locations\\\/carreteras-1\\\/\",\"url\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/ai-locations\\\/carreteras-1\\\/\",\"name\":\"Rodar en Carreteras - Spain Film Commission\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#website\"},\"datePublished\":\"2025-02-27T18:47:41+00:00\",\"dateModified\":\"2025-04-21T16:51:52+00:00\",\"description\":\"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Carreteras\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/ai-locations\\\/carreteras-1\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/ai-locations\\\/carreteras-1\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/ai-locations\\\/carreteras-1\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Carreteras\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/\",\"name\":\"Spain Film Commission\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#organization\",\"name\":\"Spain Film Commission\",\"url\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/spainfilmcommission.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/SPC_COLOR.png\",\"contentUrl\":\"https:\\\/\\\/spainfilmcommission.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/SPC_COLOR.png\",\"width\":1665,\"height\":1665,\"caption\":\"Spain Film Commission\"},\"image\":{\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rodar en Carreteras - Spain Film Commission","description":"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Carreteras","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/carreteras-1\/","og_locale":"en_US","og_type":"article","og_title":"Rodar en Carreteras - Spain Film Commission","og_description":"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Carreteras","og_url":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/carreteras-1\/","og_site_name":"Spain Film Commission","article_modified_time":"2025-04-21T16:51:52+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/carreteras-1\/","url":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/carreteras-1\/","name":"Rodar en Carreteras - Spain Film Commission","isPartOf":{"@id":"https:\/\/spainfilmcommission.com\/en\/#website"},"datePublished":"2025-02-27T18:47:41+00:00","dateModified":"2025-04-21T16:51:52+00:00","description":"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Carreteras","breadcrumb":{"@id":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/carreteras-1\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/spainfilmcommission.com\/en\/ai-locations\/carreteras-1\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/carreteras-1\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/spainfilmcommission.com\/en\/"},{"@type":"ListItem","position":2,"name":"Carreteras"}]},{"@type":"WebSite","@id":"https:\/\/spainfilmcommission.com\/en\/#website","url":"https:\/\/spainfilmcommission.com\/en\/","name":"Spain Film Commission","description":"","publisher":{"@id":"https:\/\/spainfilmcommission.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/spainfilmcommission.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/spainfilmcommission.com\/en\/#organization","name":"Spain Film Commission","url":"https:\/\/spainfilmcommission.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/spainfilmcommission.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2024\/07\/SPC_COLOR.png","contentUrl":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2024\/07\/SPC_COLOR.png","width":1665,"height":1665,"caption":"Spain Film Commission"},"image":{"@id":"https:\/\/spainfilmcommission.com\/en\/#\/schema\/logo\/image\/"}}]}},"socio":[{"ID":"39","user_login":"bilbao-bizkaia-film-commission","user_nicename":"bilbao-bizkaia-film-commission","display_name":"bilbao-bizkaia-film-commission","user_pass":"****************","user_email":"info@bifilmcommission.com","user_url":"","user_registered":"2024-12-19 17:33:51","id":39}],"nombrees":"Carreteras","nombreen":"Roads","localidad":"Los Monegros","provincia":"Zaragoza","coordenadas_maps":",","latitud":[],"longitud":[],"direcciones":"","direccionen":"","cod_postal":[],"telefono":"","fax":"","mail":"","web":"http:\/\/www.losmonegros.com\/filmcommission","descripciones":"Rectas y carreteras secundarias con poco tr\u00e1fico, en la gran llanura monegrina.","descripcionen":"","galeria":[{"ID":"20875","post_author":"2","post_date":"2025-03-08 02:51:15","post_date_gmt":"2025-03-08 01:51:15","post_content":"","post_title":"foto-779_6575","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"foto-779_6575","to_ping":"","pinged":"","post_modified":"2025-04-21 18:51:52","post_modified_gmt":"2025-04-21 16:51:52","post_content_filtered":"","post_parent":"11808","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/foto-779_6575.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"20875"},{"ID":"20877","post_author":"2","post_date":"2025-03-08 02:51:17","post_date_gmt":"2025-03-08 01:51:17","post_content":"","post_title":"foto-779_6576","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"foto-779_6576","to_ping":"","pinged":"","post_modified":"2025-04-21 18:51:52","post_modified_gmt":"2025-04-21 16:51:52","post_content_filtered":"","post_parent":"11808","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/foto-779_6576.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"20877"},{"ID":"20879","post_author":"2","post_date":"2025-03-08 02:51:19","post_date_gmt":"2025-03-08 01:51:19","post_content":"","post_title":"foto-779_6578","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"foto-779_6578","to_ping":"","pinged":"","post_modified":"2025-04-21 18:51:52","post_modified_gmt":"2025-04-21 16:51:52","post_content_filtered":"","post_parent":"11808","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/foto-779_6578.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"20879"},{"ID":"20881","post_author":"2","post_date":"2025-03-08 02:51:20","post_date_gmt":"2025-03-08 01:51:20","post_content":"","post_title":"foto-779_6579","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"foto-779_6579","to_ping":"","pinged":"","post_modified":"2025-04-21 18:51:52","post_modified_gmt":"2025-04-21 16:51:52","post_content_filtered":"","post_parent":"11808","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/foto-779_6579.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"20881"},{"ID":"20883","post_author":"2","post_date":"2025-03-08 02:51:24","post_date_gmt":"2025-03-08 01:51:24","post_content":"","post_title":"foto-779_6580","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"foto-779_6580","to_ping":"","pinged":"","post_modified":"2025-04-21 18:51:52","post_modified_gmt":"2025-04-21 16:51:52","post_content_filtered":"","post_parent":"11808","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/foto-779_6580.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"20883"},{"ID":"20885","post_author":"2","post_date":"2025-03-08 02:51:26","post_date_gmt":"2025-03-08 01:51:26","post_content":"","post_title":"foto-779_6581","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"foto-779_6581","to_ping":"","pinged":"","post_modified":"2025-04-21 18:51:52","post_modified_gmt":"2025-04-21 16:51:52","post_content_filtered":"","post_parent":"11808","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/foto-779_6581.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"20885"},{"ID":"20887","post_author":"2","post_date":"2025-03-08 02:51:27","post_date_gmt":"2025-03-08 01:51:27","post_content":"","post_title":"foto-779_6582","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"foto-779_6582","to_ping":"","pinged":"","post_modified":"2025-04-21 18:51:52","post_modified_gmt":"2025-04-21 16:51:52","post_content_filtered":"","post_parent":"11808","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/foto-779_6582.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"20887"},{"ID":"20889","post_author":"2","post_date":"2025-03-08 02:51:29","post_date_gmt":"2025-03-08 01:51:29","post_content":"","post_title":"foto-779_6583","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"foto-779_6583","to_ping":"","pinged":"","post_modified":"2025-04-21 18:51:52","post_modified_gmt":"2025-04-21 16:51:52","post_content_filtered":"","post_parent":"11808","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/foto-779_6583.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"20889"},{"ID":"20891","post_author":"2","post_date":"2025-03-08 02:51:31","post_date_gmt":"2025-03-08 01:51:31","post_content":"","post_title":"foto-779_6584","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"foto-779_6584","to_ping":"","pinged":"","post_modified":"2025-04-21 18:51:52","post_modified_gmt":"2025-04-21 16:51:52","post_content_filtered":"","post_parent":"11808","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/foto-779_6584.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"20891"},{"ID":"20893","post_author":"2","post_date":"2025-03-08 02:51:33","post_date_gmt":"2025-03-08 01:51:33","post_content":"","post_title":"foto-779_6585","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"foto-779_6585","to_ping":"","pinged":"","post_modified":"2025-04-21 18:51:52","post_modified_gmt":"2025-04-21 16:51:52","post_content_filtered":"","post_parent":"11808","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/foto-779_6585.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"20893"},{"ID":"20895","post_author":"2","post_date":"2025-03-08 02:51:35","post_date_gmt":"2025-03-08 01:51:35","post_content":"","post_title":"foto-779_8451","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"foto-779_8451","to_ping":"","pinged":"","post_modified":"2025-04-21 18:51:52","post_modified_gmt":"2025-04-21 16:51:52","post_content_filtered":"","post_parent":"11808","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/foto-779_8451.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"20895"},{"ID":"20897","post_author":"2","post_date":"2025-03-08 02:51:37","post_date_gmt":"2025-03-08 01:51:37","post_content":"","post_title":"foto-779_8452","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"foto-779_8452","to_ping":"","pinged":"","post_modified":"2025-04-21 18:51:52","post_modified_gmt":"2025-04-21 16:51:52","post_content_filtered":"","post_parent":"11808","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/foto-779_8452.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"20897"}],"nombrepaginaes":"carreteras-1","nombrepaginaen":"roads-1","latitud_gps":"","longitud_gps":"","adicionaleses":"Permisos obligatorios.","adicionalesen":"","videoes":"","videoen":"","video2es":"","video2en":"","_links":{"self":[{"href":"https:\/\/spainfilmcommission.com\/en\/wp-json\/wp\/v2\/localizaciones\/localizacion\/11808","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/spainfilmcommission.com\/en\/wp-json\/wp\/v2\/localizaciones\/localizacion"}],"about":[{"href":"https:\/\/spainfilmcommission.com\/en\/wp-json\/wp\/v2\/types\/localizacion"}],"author":[{"embeddable":true,"href":"https:\/\/spainfilmcommission.com\/en\/wp-json\/wp\/v2\/users\/2"}],"wp:attachment":[{"href":"https:\/\/spainfilmcommission.com\/en\/wp-json\/wp\/v2\/media?parent=11808"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}