{"id":11707,"date":"2025-02-27T19:46:30","date_gmt":"2025-02-27T18:46:30","guid":{"rendered":"https:\/\/spainfilmcommission.com\/?post_type=localizacion&#038;p=11707"},"modified":"2025-04-21T12:01:15","modified_gmt":"2025-04-21T10:01:15","slug":"puente-de-triana","status":"publish","type":"localizacion","link":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/puente-de-triana\/","title":{"rendered":"Puente de Triana"},"content":{"rendered":"","protected":false},"author":2,"template":"","meta":[],"class_list":["post-11707","localizacion","type-localizacion","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rodar en Puente de Triana - Spain Film Commission<\/title>\n<meta name=\"description\" content=\"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Puente de Triana\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/spainfilmcommission.com\/en\/ai-locations\/puente-de-triana\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rodar en Puente de Triana - Spain Film Commission\" \/>\n<meta property=\"og:description\" content=\"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Puente de Triana\" \/>\n<meta property=\"og:url\" content=\"https:\/\/spainfilmcommission.com\/en\/ai-locations\/puente-de-triana\/\" \/>\n<meta property=\"og:site_name\" content=\"Spain Film Commission\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-21T10:01:15+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/ai-locations\\\/puente-de-triana\\\/\",\"url\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/ai-locations\\\/puente-de-triana\\\/\",\"name\":\"Rodar en Puente de Triana - Spain Film Commission\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#website\"},\"datePublished\":\"2025-02-27T18:46:30+00:00\",\"dateModified\":\"2025-04-21T10:01:15+00:00\",\"description\":\"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Puente de Triana\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/ai-locations\\\/puente-de-triana\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/ai-locations\\\/puente-de-triana\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/ai-locations\\\/puente-de-triana\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Puente de Triana\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/\",\"name\":\"Spain Film Commission\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#organization\",\"name\":\"Spain Film Commission\",\"url\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/spainfilmcommission.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/SPC_COLOR.png\",\"contentUrl\":\"https:\\\/\\\/spainfilmcommission.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/SPC_COLOR.png\",\"width\":1665,\"height\":1665,\"caption\":\"Spain Film Commission\"},\"image\":{\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rodar en Puente de Triana - Spain Film Commission","description":"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Puente de Triana","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/puente-de-triana\/","og_locale":"en_US","og_type":"article","og_title":"Rodar en Puente de Triana - Spain Film Commission","og_description":"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Puente de Triana","og_url":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/puente-de-triana\/","og_site_name":"Spain Film Commission","article_modified_time":"2025-04-21T10:01:15+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/puente-de-triana\/","url":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/puente-de-triana\/","name":"Rodar en Puente de Triana - Spain Film Commission","isPartOf":{"@id":"https:\/\/spainfilmcommission.com\/en\/#website"},"datePublished":"2025-02-27T18:46:30+00:00","dateModified":"2025-04-21T10:01:15+00:00","description":"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Puente de Triana","breadcrumb":{"@id":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/puente-de-triana\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/spainfilmcommission.com\/en\/ai-locations\/puente-de-triana\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/puente-de-triana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/spainfilmcommission.com\/en\/"},{"@type":"ListItem","position":2,"name":"Puente de Triana"}]},{"@type":"WebSite","@id":"https:\/\/spainfilmcommission.com\/en\/#website","url":"https:\/\/spainfilmcommission.com\/en\/","name":"Spain Film Commission","description":"","publisher":{"@id":"https:\/\/spainfilmcommission.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/spainfilmcommission.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/spainfilmcommission.com\/en\/#organization","name":"Spain Film Commission","url":"https:\/\/spainfilmcommission.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/spainfilmcommission.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2024\/07\/SPC_COLOR.png","contentUrl":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2024\/07\/SPC_COLOR.png","width":1665,"height":1665,"caption":"Spain Film Commission"},"image":{"@id":"https:\/\/spainfilmcommission.com\/en\/#\/schema\/logo\/image\/"}}]}},"socio":[{"ID":"10","user_login":"andalucia-film-commission","user_nicename":"andalucia-film-commission","display_name":"andalucia-film-commission","user_pass":"****************","user_email":"info@andaluciafilm.com","user_url":"","user_registered":"2024-12-19 07:26:16","id":10}],"nombrees":"Puente de Triana","nombreen":"Triana Bridge","localidad":"Sevilla","provincia":"Sevilla","coordenadas_maps":"37.387051, -6.002303","latitud":"37.387051000000","longitud":"-6.002303000000","direcciones":"","direccionen":"","cod_postal":[],"telefono":"","fax":"","mail":"","web":"","descripciones":"Posiblemente uno de los barrios m\u00e1s populares de la ciudad de Sevilla, est\u00e1 situado en la orilla este del r\u00edo Guadalquivir y est\u00e1 unido a la ciudad por el Puente de Triana, que sustituy\u00f3 al antiguo Puente de Barcas. Poseedor de una identidad propia, al mismo tiempo, refuerza la idiosincrasia de la capital sevillana, con su apego a tradiciones como la Semana Santa o el flamenco. Son muy caracter\u00edsticas de Triana las casas de vecinos o corrales y la cer\u00e1mica, y en \u00e9l han nacido numerosos artistas, cantantes, bailaores y toreros.","descripcionen":"Possibly one of the most popular quarters in the city of Seville, it is situated by the east shore of the Guadalquivir river and is connected to the city by the Triana bridge, which replaced the old Barcas bridge. While it has a unique identity, at the same time it strengthens the idiosyncrasy of the Sevillian capital, with its devotion to traditions such as the Holy Week or flamenco. Traditional patio housing and ceramics are very characteristic of this quarter and this is the birthplace of many artists, singers, dancers and bullfighters.","galeria":[{"ID":"19095","post_author":"2","post_date":"2025-03-08 02:18:54","post_date_gmt":"2025-03-08 01:18:54","post_content":"","post_title":"foto-677_5506","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"foto-677_5506","to_ping":"","pinged":"","post_modified":"2025-04-21 12:01:15","post_modified_gmt":"2025-04-21 10:01:15","post_content_filtered":"","post_parent":"11707","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/foto-677_5506.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"19095"},{"ID":"19097","post_author":"2","post_date":"2025-03-08 02:18:56","post_date_gmt":"2025-03-08 01:18:56","post_content":"","post_title":"foto-677_5507","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"foto-677_5507","to_ping":"","pinged":"","post_modified":"2025-04-21 12:01:15","post_modified_gmt":"2025-04-21 10:01:15","post_content_filtered":"","post_parent":"11707","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/foto-677_5507.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"19097"}],"nombrepaginaes":"puente-de-triana","nombrepaginaen":"triana-bridge","latitud_gps":"","longitud_gps":"","adicionaleses":"","adicionalesen":"","videoes":"","videoen":"","video2es":"","video2en":"","_links":{"self":[{"href":"https:\/\/spainfilmcommission.com\/en\/wp-json\/wp\/v2\/localizaciones\/localizacion\/11707","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/spainfilmcommission.com\/en\/wp-json\/wp\/v2\/localizaciones\/localizacion"}],"about":[{"href":"https:\/\/spainfilmcommission.com\/en\/wp-json\/wp\/v2\/types\/localizacion"}],"author":[{"embeddable":true,"href":"https:\/\/spainfilmcommission.com\/en\/wp-json\/wp\/v2\/users\/2"}],"wp:attachment":[{"href":"https:\/\/spainfilmcommission.com\/en\/wp-json\/wp\/v2\/media?parent=11707"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}