{"id":11594,"date":"2025-02-27T18:38:36","date_gmt":"2025-02-27T17:38:36","guid":{"rendered":"https:\/\/spainfilmcommission.com\/?post_type=localizacion&#038;p=11594"},"modified":"2025-04-22T08:22:19","modified_gmt":"2025-04-22T06:22:19","slug":"catedral-de-santa-maria","status":"publish","type":"localizacion","link":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/catedral-de-santa-maria\/","title":{"rendered":"Catedral de Santa Mar\u00eda"},"content":{"rendered":"","protected":false},"author":2,"template":"","meta":[],"class_list":["post-11594","localizacion","type-localizacion","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rodar en Catedral de Santa Mar\u00eda - Spain Film Commission<\/title>\n<meta name=\"description\" content=\"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Catedral de Santa Mar\u00eda\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/spainfilmcommission.com\/en\/ai-locations\/catedral-de-santa-maria\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rodar en Catedral de Santa Mar\u00eda - Spain Film Commission\" \/>\n<meta property=\"og:description\" content=\"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Catedral de Santa Mar\u00eda\" \/>\n<meta property=\"og:url\" content=\"https:\/\/spainfilmcommission.com\/en\/ai-locations\/catedral-de-santa-maria\/\" \/>\n<meta property=\"og:site_name\" content=\"Spain Film Commission\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-22T06:22:19+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/ai-locations\\\/catedral-de-santa-maria\\\/\",\"url\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/ai-locations\\\/catedral-de-santa-maria\\\/\",\"name\":\"Rodar en Catedral de Santa Mar\u00eda - Spain Film Commission\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#website\"},\"datePublished\":\"2025-02-27T17:38:36+00:00\",\"dateModified\":\"2025-04-22T06:22:19+00:00\",\"description\":\"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Catedral de Santa Mar\u00eda\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/ai-locations\\\/catedral-de-santa-maria\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/ai-locations\\\/catedral-de-santa-maria\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/ai-locations\\\/catedral-de-santa-maria\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Catedral de Santa Mar\u00eda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/\",\"name\":\"Spain Film Commission\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#organization\",\"name\":\"Spain Film Commission\",\"url\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/spainfilmcommission.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/SPC_COLOR.png\",\"contentUrl\":\"https:\\\/\\\/spainfilmcommission.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/SPC_COLOR.png\",\"width\":1665,\"height\":1665,\"caption\":\"Spain Film Commission\"},\"image\":{\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rodar en Catedral de Santa Mar\u00eda - Spain Film Commission","description":"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Catedral de Santa Mar\u00eda","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/catedral-de-santa-maria\/","og_locale":"en_US","og_type":"article","og_title":"Rodar en Catedral de Santa Mar\u00eda - Spain Film Commission","og_description":"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Catedral de Santa Mar\u00eda","og_url":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/catedral-de-santa-maria\/","og_site_name":"Spain Film Commission","article_modified_time":"2025-04-22T06:22:19+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/catedral-de-santa-maria\/","url":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/catedral-de-santa-maria\/","name":"Rodar en Catedral de Santa Mar\u00eda - Spain Film Commission","isPartOf":{"@id":"https:\/\/spainfilmcommission.com\/en\/#website"},"datePublished":"2025-02-27T17:38:36+00:00","dateModified":"2025-04-22T06:22:19+00:00","description":"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Catedral de Santa Mar\u00eda","breadcrumb":{"@id":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/catedral-de-santa-maria\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/spainfilmcommission.com\/en\/ai-locations\/catedral-de-santa-maria\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/catedral-de-santa-maria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/spainfilmcommission.com\/en\/"},{"@type":"ListItem","position":2,"name":"Catedral de Santa Mar\u00eda"}]},{"@type":"WebSite","@id":"https:\/\/spainfilmcommission.com\/en\/#website","url":"https:\/\/spainfilmcommission.com\/en\/","name":"Spain Film Commission","description":"","publisher":{"@id":"https:\/\/spainfilmcommission.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/spainfilmcommission.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/spainfilmcommission.com\/en\/#organization","name":"Spain Film Commission","url":"https:\/\/spainfilmcommission.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/spainfilmcommission.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2024\/07\/SPC_COLOR.png","contentUrl":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2024\/07\/SPC_COLOR.png","width":1665,"height":1665,"caption":"Spain Film Commission"},"image":{"@id":"https:\/\/spainfilmcommission.com\/en\/#\/schema\/logo\/image\/"}}]}},"socio":[{"ID":"11","user_login":"vitoria-gasteiz-film-office","user_nicename":"vitoria-gasteiz-film-office","display_name":"vitoria-gasteiz-film-office","user_pass":"****************","user_email":"filmoffice@vitoria-gasteiz.org","user_url":"","user_registered":"2024-12-19 13:09:52","id":11}],"nombrees":"Catedral de Santa Mar\u00eda","nombreen":"Santa Mar\u00eda Cathedral","localidad":"Vitoria-Gasteiz","provincia":"\u00c1lava","coordenadas_maps":"42.850807, -2.672730","latitud":"42.850807000000","longitud":"-2.672730000000","direcciones":"","direccionen":"","cod_postal":[],"telefono":"","fax":"","mail":"","web":"http:\/\/www.catedralvitoria.eus\/index.php","descripciones":"La catedral de Santa Mar\u00eda de Vitoria, conocida popularmente como Catedral Vieja, es un templo religioso de estilo g\u00f3tico situado en el Casco Hist\u00f3rico de Vitoria-Gasteiz. Desde el a\u00f1o 2015, el templo est\u00e1 en la lista de monumentos Patrimonio de la Humanidad de la UNESCO por su singularidad arquitect\u00f3nica. La Catedral de Santa Mar\u00eda ha seducido a escritores e intelectuales de renombre internacional como Ken Follet, quien se inspir\u00f3 en la catedral para escribir la segunda parte de Los Pilares de la Tierra.","descripcionen":"The Cathedral of Santa Mar\u00eda, popularly known as \"The Old Cathedral\", is a Gothic style Cathedral situated at the Old Town of Vitoria-Gasteiz. From the year 2015, the temple is in the UNESCO's monuments World Heritage list, for its arquitectural singularity. Santa Maria Cathedral has attracted writers and intellectuals of international renown such as Ken Follett, who was inspired by the Cathedral to write the second part of \"The Pillars of the Earth\".","galeria":[{"ID":"17157","post_author":"2","post_date":"2025-03-08 00:03:44","post_date_gmt":"2025-03-07 23:03:44","post_content":"","post_title":"foto-556_4130","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"foto-556_4130","to_ping":"","pinged":"","post_modified":"2025-04-22 08:22:19","post_modified_gmt":"2025-04-22 06:22:19","post_content_filtered":"","post_parent":"11594","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/foto-556_4130.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"17157"},{"ID":"17159","post_author":"2","post_date":"2025-03-08 00:03:46","post_date_gmt":"2025-03-07 23:03:46","post_content":"","post_title":"foto-556_4131","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"foto-556_4131","to_ping":"","pinged":"","post_modified":"2025-04-22 08:22:19","post_modified_gmt":"2025-04-22 06:22:19","post_content_filtered":"","post_parent":"11594","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/foto-556_4131.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"17159"},{"ID":"17161","post_author":"2","post_date":"2025-03-08 00:03:49","post_date_gmt":"2025-03-07 23:03:49","post_content":"","post_title":"foto-556_4132","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"foto-556_4132","to_ping":"","pinged":"","post_modified":"2025-04-22 08:22:19","post_modified_gmt":"2025-04-22 06:22:19","post_content_filtered":"","post_parent":"11594","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/foto-556_4132.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"17161"},{"ID":"17163","post_author":"2","post_date":"2025-03-08 00:03:51","post_date_gmt":"2025-03-07 23:03:51","post_content":"","post_title":"foto-556_4133","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"foto-556_4133","to_ping":"","pinged":"","post_modified":"2025-04-22 08:22:19","post_modified_gmt":"2025-04-22 06:22:19","post_content_filtered":"","post_parent":"11594","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/foto-556_4133.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"17163"}],"nombrepaginaes":"catedral-de-santa-maria","nombrepaginaen":"santa-maria-cathedral","latitud_gps":"42\u00b051'02.9\"N","longitud_gps":"2\u00b040'21.8\"W","adicionaleses":"","adicionalesen":"","videoes":"","videoen":"","video2es":"","video2en":"","_links":{"self":[{"href":"https:\/\/spainfilmcommission.com\/en\/wp-json\/wp\/v2\/localizaciones\/localizacion\/11594","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/spainfilmcommission.com\/en\/wp-json\/wp\/v2\/localizaciones\/localizacion"}],"about":[{"href":"https:\/\/spainfilmcommission.com\/en\/wp-json\/wp\/v2\/types\/localizacion"}],"author":[{"embeddable":true,"href":"https:\/\/spainfilmcommission.com\/en\/wp-json\/wp\/v2\/users\/2"}],"wp:attachment":[{"href":"https:\/\/spainfilmcommission.com\/en\/wp-json\/wp\/v2\/media?parent=11594"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}