{"id":11572,"date":"2025-02-27T18:38:36","date_gmt":"2025-02-27T17:38:36","guid":{"rendered":"https:\/\/spainfilmcommission.com\/?post_type=localizacion&#038;p=11572"},"modified":"2025-04-21T13:20:57","modified_gmt":"2025-04-21T11:20:57","slug":"bosque-de-oma","status":"publish","type":"localizacion","link":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/bosque-de-oma\/","title":{"rendered":"Bosque de Oma"},"content":{"rendered":"","protected":false},"author":2,"template":"","meta":[],"class_list":["post-11572","localizacion","type-localizacion","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rodar en Bosque de Oma - Spain Film Commission<\/title>\n<meta name=\"description\" content=\"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Bosque de Oma\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/spainfilmcommission.com\/en\/ai-locations\/bosque-de-oma\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rodar en Bosque de Oma - Spain Film Commission\" \/>\n<meta property=\"og:description\" content=\"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Bosque de Oma\" \/>\n<meta property=\"og:url\" content=\"https:\/\/spainfilmcommission.com\/en\/ai-locations\/bosque-de-oma\/\" \/>\n<meta property=\"og:site_name\" content=\"Spain Film Commission\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-21T11:20:57+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/ai-locations\\\/bosque-de-oma\\\/\",\"url\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/ai-locations\\\/bosque-de-oma\\\/\",\"name\":\"Rodar en Bosque de Oma - Spain Film Commission\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#website\"},\"datePublished\":\"2025-02-27T17:38:36+00:00\",\"dateModified\":\"2025-04-21T11:20:57+00:00\",\"description\":\"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Bosque de Oma\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/ai-locations\\\/bosque-de-oma\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/ai-locations\\\/bosque-de-oma\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/ai-locations\\\/bosque-de-oma\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bosque de Oma\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/\",\"name\":\"Spain Film Commission\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#organization\",\"name\":\"Spain Film Commission\",\"url\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/spainfilmcommission.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/SPC_COLOR.png\",\"contentUrl\":\"https:\\\/\\\/spainfilmcommission.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/SPC_COLOR.png\",\"width\":1665,\"height\":1665,\"caption\":\"Spain Film Commission\"},\"image\":{\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rodar en Bosque de Oma - Spain Film Commission","description":"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Bosque de Oma","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/bosque-de-oma\/","og_locale":"en_US","og_type":"article","og_title":"Rodar en Bosque de Oma - Spain Film Commission","og_description":"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Bosque de Oma","og_url":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/bosque-de-oma\/","og_site_name":"Spain Film Commission","article_modified_time":"2025-04-21T11:20:57+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/bosque-de-oma\/","url":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/bosque-de-oma\/","name":"Rodar en Bosque de Oma - Spain Film Commission","isPartOf":{"@id":"https:\/\/spainfilmcommission.com\/en\/#website"},"datePublished":"2025-02-27T17:38:36+00:00","dateModified":"2025-04-21T11:20:57+00:00","description":"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Bosque de Oma","breadcrumb":{"@id":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/bosque-de-oma\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/spainfilmcommission.com\/en\/ai-locations\/bosque-de-oma\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/bosque-de-oma\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/spainfilmcommission.com\/en\/"},{"@type":"ListItem","position":2,"name":"Bosque de Oma"}]},{"@type":"WebSite","@id":"https:\/\/spainfilmcommission.com\/en\/#website","url":"https:\/\/spainfilmcommission.com\/en\/","name":"Spain Film Commission","description":"","publisher":{"@id":"https:\/\/spainfilmcommission.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/spainfilmcommission.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/spainfilmcommission.com\/en\/#organization","name":"Spain Film Commission","url":"https:\/\/spainfilmcommission.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/spainfilmcommission.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2024\/07\/SPC_COLOR.png","contentUrl":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2024\/07\/SPC_COLOR.png","width":1665,"height":1665,"caption":"Spain Film Commission"},"image":{"@id":"https:\/\/spainfilmcommission.com\/en\/#\/schema\/logo\/image\/"}}]}},"socio":[{"ID":"39","user_login":"bilbao-bizkaia-film-commission","user_nicename":"bilbao-bizkaia-film-commission","display_name":"bilbao-bizkaia-film-commission","user_pass":"****************","user_email":"info@bifilmcommission.com","user_url":"","user_registered":"2024-12-19 17:33:51","id":39}],"nombrees":"Bosque de Oma","nombreen":"Oma Forest","localidad":"Kortezubi","provincia":"Vizcaya","coordenadas_maps":"43.337976, 2.624295","latitud":"43.337976000000","longitud":"2.624295000000","direcciones":"","direccionen":"","cod_postal":[],"telefono":"","fax":"","mail":"","web":"","descripciones":"El bosque de Oma, es una obra art\u00edstica creada por el escultor y pintor Ibarrola entre los a\u00f1os 1982 y 1985 y que se puede encuadrar dentro de la tendencia contempor\u00e1nea del Land Art.\u00a0 Dicho bosque est\u00e1 situado en la Reserva de la Biosfera de Urdaibai y consiste en un grupo de \u00e1rboles en los que se han realizado pintadas y que en el conjunto de varios troncos y mirando desde determinadas posiciones, componen diferentes figuras geom\u00e9tricas, humanas y animales. La obra se encuentra ubicada en una de las laderas del valle de Oma, en la localidad de Kortezubi, cerca de la cueva de Santimami\u00f1e, no muy lejos del antiguo domicilio del artista. El pintor y escultor Agust\u00edn Ibarrola concibi\u00f3 el bosque animado o bosque de Oma como una muestra de la relaci\u00f3n entre la naturaleza y la presencia humana.","descripcionen":"Oma forest is a work of art created by Agust\u00edn Ibarrola, a Basque sculptor and painter. The work is located in a forest near kortezubi (Bizkaia, Basque Country), in the natural reserve of Urdaibai. It is also Known as the \"painted forest\". The work follows the modern art trend called \"Land Art\". Most of the trees are Monterrey pines. The projects aims to display the horrible and ghastly harmony between nature and human presence by painting on the trunks of trees, human figures, animals and geometric shapes, some of which are visible only from certain positions.","galeria":[{"ID":"16729","post_author":"2","post_date":"2025-03-07 23:56:20","post_date_gmt":"2025-03-07 22:56:20","post_content":"","post_title":"foto-534_3922","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"foto-534_3922","to_ping":"","pinged":"","post_modified":"2025-04-21 13:20:57","post_modified_gmt":"2025-04-21 11:20:57","post_content_filtered":"","post_parent":"11572","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/foto-534_3922.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"16729"},{"ID":"16731","post_author":"2","post_date":"2025-03-07 23:56:22","post_date_gmt":"2025-03-07 22:56:22","post_content":"","post_title":"foto-534_3923","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"foto-534_3923","to_ping":"","pinged":"","post_modified":"2025-04-21 13:20:57","post_modified_gmt":"2025-04-21 11:20:57","post_content_filtered":"","post_parent":"11572","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/foto-534_3923.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"16731"},{"ID":"16733","post_author":"2","post_date":"2025-03-07 23:56:24","post_date_gmt":"2025-03-07 22:56:24","post_content":"","post_title":"foto-534_3924","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"foto-534_3924","to_ping":"","pinged":"","post_modified":"2025-04-21 13:20:57","post_modified_gmt":"2025-04-21 11:20:57","post_content_filtered":"","post_parent":"11572","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/foto-534_3924.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"16733"},{"ID":"16735","post_author":"2","post_date":"2025-03-07 23:56:26","post_date_gmt":"2025-03-07 22:56:26","post_content":"","post_title":"foto-534_3925","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"foto-534_3925","to_ping":"","pinged":"","post_modified":"2025-04-21 13:20:57","post_modified_gmt":"2025-04-21 11:20:57","post_content_filtered":"","post_parent":"11572","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/foto-534_3925.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"16735"},{"ID":"16737","post_author":"2","post_date":"2025-03-07 23:56:28","post_date_gmt":"2025-03-07 22:56:28","post_content":"","post_title":"foto-534_3926","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"foto-534_3926","to_ping":"","pinged":"","post_modified":"2025-04-21 13:20:57","post_modified_gmt":"2025-04-21 11:20:57","post_content_filtered":"","post_parent":"11572","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/foto-534_3926.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"16737"},{"ID":"16739","post_author":"2","post_date":"2025-03-07 23:56:30","post_date_gmt":"2025-03-07 22:56:30","post_content":"","post_title":"foto-534_3927","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"foto-534_3927","to_ping":"","pinged":"","post_modified":"2025-04-21 13:20:57","post_modified_gmt":"2025-04-21 11:20:57","post_content_filtered":"","post_parent":"11572","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/foto-534_3927.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"16739"},{"ID":"16741","post_author":"2","post_date":"2025-03-07 23:56:32","post_date_gmt":"2025-03-07 22:56:32","post_content":"","post_title":"foto-534_3928","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"foto-534_3928","to_ping":"","pinged":"","post_modified":"2025-04-21 13:20:57","post_modified_gmt":"2025-04-21 11:20:57","post_content_filtered":"","post_parent":"11572","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/foto-534_3928.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"16741"},{"ID":"16743","post_author":"2","post_date":"2025-03-07 23:56:34","post_date_gmt":"2025-03-07 22:56:34","post_content":"","post_title":"foto-534_3929","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"foto-534_3929","to_ping":"","pinged":"","post_modified":"2025-04-21 13:20:57","post_modified_gmt":"2025-04-21 11:20:57","post_content_filtered":"","post_parent":"11572","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/foto-534_3929.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"16743"},{"ID":"16745","post_author":"2","post_date":"2025-03-07 23:56:36","post_date_gmt":"2025-03-07 22:56:36","post_content":"","post_title":"foto-534_3930","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"foto-534_3930","to_ping":"","pinged":"","post_modified":"2025-04-21 13:20:57","post_modified_gmt":"2025-04-21 11:20:57","post_content_filtered":"","post_parent":"11572","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/foto-534_3930.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"16745"}],"nombrepaginaes":"bosque-de-oma","nombrepaginaen":"oma-forest","latitud_gps":"43\u00b0 20","longitud_gps":"2\u00b0 38","adicionaleses":"","adicionalesen":"","videoes":"","videoen":"","video2es":"","video2en":"","_links":{"self":[{"href":"https:\/\/spainfilmcommission.com\/en\/wp-json\/wp\/v2\/localizaciones\/localizacion\/11572","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/spainfilmcommission.com\/en\/wp-json\/wp\/v2\/localizaciones\/localizacion"}],"about":[{"href":"https:\/\/spainfilmcommission.com\/en\/wp-json\/wp\/v2\/types\/localizacion"}],"author":[{"embeddable":true,"href":"https:\/\/spainfilmcommission.com\/en\/wp-json\/wp\/v2\/users\/2"}],"wp:attachment":[{"href":"https:\/\/spainfilmcommission.com\/en\/wp-json\/wp\/v2\/media?parent=11572"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}