{"id":11550,"date":"2025-02-27T18:37:19","date_gmt":"2025-02-27T17:37:19","guid":{"rendered":"https:\/\/spainfilmcommission.com\/?post_type=localizacion&#038;p=11550"},"modified":"2025-04-22T09:24:14","modified_gmt":"2025-04-22T07:24:14","slug":"la-cuevona-de-cuevas","status":"publish","type":"localizacion","link":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/la-cuevona-de-cuevas\/","title":{"rendered":"La Cuevona de Cuevas"},"content":{"rendered":"","protected":false},"author":2,"template":"","meta":[],"class_list":["post-11550","localizacion","type-localizacion","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rodar en La Cuevona de Cuevas - Spain Film Commission<\/title>\n<meta name=\"description\" content=\"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en La Cuevona de Cuevas\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/spainfilmcommission.com\/en\/ai-locations\/la-cuevona-de-cuevas\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rodar en La Cuevona de Cuevas - Spain Film Commission\" \/>\n<meta property=\"og:description\" content=\"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en La Cuevona de Cuevas\" \/>\n<meta property=\"og:url\" content=\"https:\/\/spainfilmcommission.com\/en\/ai-locations\/la-cuevona-de-cuevas\/\" \/>\n<meta property=\"og:site_name\" content=\"Spain Film Commission\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-22T07:24:14+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/ai-locations\\\/la-cuevona-de-cuevas\\\/\",\"url\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/ai-locations\\\/la-cuevona-de-cuevas\\\/\",\"name\":\"Rodar en La Cuevona de Cuevas - Spain Film Commission\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#website\"},\"datePublished\":\"2025-02-27T17:37:19+00:00\",\"dateModified\":\"2025-04-22T07:24:14+00:00\",\"description\":\"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en La Cuevona de Cuevas\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/ai-locations\\\/la-cuevona-de-cuevas\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/ai-locations\\\/la-cuevona-de-cuevas\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/ai-locations\\\/la-cuevona-de-cuevas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Cuevona de Cuevas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/\",\"name\":\"Spain Film Commission\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#organization\",\"name\":\"Spain Film Commission\",\"url\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/spainfilmcommission.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/SPC_COLOR.png\",\"contentUrl\":\"https:\\\/\\\/spainfilmcommission.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/SPC_COLOR.png\",\"width\":1665,\"height\":1665,\"caption\":\"Spain Film Commission\"},\"image\":{\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rodar en La Cuevona de Cuevas - Spain Film Commission","description":"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en La Cuevona de Cuevas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/la-cuevona-de-cuevas\/","og_locale":"en_US","og_type":"article","og_title":"Rodar en La Cuevona de Cuevas - Spain Film Commission","og_description":"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en La Cuevona de Cuevas","og_url":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/la-cuevona-de-cuevas\/","og_site_name":"Spain Film Commission","article_modified_time":"2025-04-22T07:24:14+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/la-cuevona-de-cuevas\/","url":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/la-cuevona-de-cuevas\/","name":"Rodar en La Cuevona de Cuevas - Spain Film Commission","isPartOf":{"@id":"https:\/\/spainfilmcommission.com\/en\/#website"},"datePublished":"2025-02-27T17:37:19+00:00","dateModified":"2025-04-22T07:24:14+00:00","description":"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en La Cuevona de Cuevas","breadcrumb":{"@id":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/la-cuevona-de-cuevas\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/spainfilmcommission.com\/en\/ai-locations\/la-cuevona-de-cuevas\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/la-cuevona-de-cuevas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/spainfilmcommission.com\/en\/"},{"@type":"ListItem","position":2,"name":"La Cuevona de Cuevas"}]},{"@type":"WebSite","@id":"https:\/\/spainfilmcommission.com\/en\/#website","url":"https:\/\/spainfilmcommission.com\/en\/","name":"Spain Film Commission","description":"","publisher":{"@id":"https:\/\/spainfilmcommission.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/spainfilmcommission.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/spainfilmcommission.com\/en\/#organization","name":"Spain Film Commission","url":"https:\/\/spainfilmcommission.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/spainfilmcommission.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2024\/07\/SPC_COLOR.png","contentUrl":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2024\/07\/SPC_COLOR.png","width":1665,"height":1665,"caption":"Spain Film Commission"},"image":{"@id":"https:\/\/spainfilmcommission.com\/en\/#\/schema\/logo\/image\/"}}]}},"socio":[{"ID":"16","user_login":"asturias-paraiso-natural-film-commission","user_nicename":"asturias-paraiso-natural-film-commission","display_name":"asturias-paraiso-natural-film-commission","user_pass":"****************","user_email":"filmcommission@turismoycultura.asturias.es","user_url":"","user_registered":"2024-12-19 13:43:43","id":16}],"nombrees":"La Cuevona de Cuevas","nombreen":"La Cuevona de Cuevas","localidad":"Junco, Ribadesella","provincia":"Asturias","coordenadas_maps":"43.4318, -5.073475","latitud":"43.431800000000","longitud":"-5.073475000000","direcciones":"","direccionen":"","cod_postal":[],"telefono":"","fax":"","mail":"","web":"https:\/\/www.turismoasturias.es\/descubre\/...\/otros...\/cuevas...\/cuevona-de-cuevas-del-agua","descripciones":"La Cuevona de Cuevas es un t\u00fanel natural o gruta de m\u00e1s de trescientos metros de longitud que se encuentra en la parroquia de Junco, perteneciente al municipio de Ribadesella (Asturias). Supone un recorrido de gran belleza paisajista, en el que el paso natural fue habilitado y aprovechado en el pasado por los vecinos y este camino se moderniz\u00f3 m\u00e1s tarde con asfalto, construyendo una verdadera carretera por la que pueden circular veh\u00edculos y peatones.\u00a0 La cueva est\u00e1 perfectamente iluminada tanto para favorecer el paso de los transe\u00fantes como para resaltar las atractivas formaciones geol\u00f3gicas.","descripcionen":"Cuevona de Cuevas is a natural tunnel or cave of 300\u00a0meters long which is located in Junco, belonging to the municipality of Ribadesella (Asturias). It is\u00a0a route of great landscaping beauty and as a natural path was enabled\u00a0in the past by the locals,\u00a0and this road was modernized later with asphalt, constructing a true highway for vehicles and pedestrians. The cave is perfectly illuminated for the\u00a0passers-by and to highlight the attractive geological formations.","galeria":[{"ID":"16315","post_author":"2","post_date":"2025-03-07 23:48:34","post_date_gmt":"2025-03-07 22:48:34","post_content":"","post_title":"foto-510_3673","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"foto-510_3673","to_ping":"","pinged":"","post_modified":"2025-04-22 09:24:15","post_modified_gmt":"2025-04-22 07:24:15","post_content_filtered":"","post_parent":"11550","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/foto-510_3673.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"16315"},{"ID":"16317","post_author":"2","post_date":"2025-03-07 23:48:36","post_date_gmt":"2025-03-07 22:48:36","post_content":"","post_title":"foto-510_3674","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"foto-510_3674","to_ping":"","pinged":"","post_modified":"2025-04-22 09:24:15","post_modified_gmt":"2025-04-22 07:24:15","post_content_filtered":"","post_parent":"11550","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/foto-510_3674.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"16317"},{"ID":"16319","post_author":"2","post_date":"2025-03-07 23:48:38","post_date_gmt":"2025-03-07 22:48:38","post_content":"","post_title":"foto-510_3675","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"foto-510_3675","to_ping":"","pinged":"","post_modified":"2025-04-22 09:24:15","post_modified_gmt":"2025-04-22 07:24:15","post_content_filtered":"","post_parent":"11550","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/foto-510_3675.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"16319"}],"nombrepaginaes":"la-cuevona-de-cuevas","nombrepaginaen":"la-cuevona-de-cuevas","latitud_gps":"434.318","longitud_gps":"-5.073.475","adicionaleses":"","adicionalesen":"","videoes":"https:\/\/www.youtube.com\/watch?v=qAVjl81KB2U","videoen":"https:\/\/www.youtube.com\/watch?v=qAVjl81KB2U","video2es":"","video2en":"","_links":{"self":[{"href":"https:\/\/spainfilmcommission.com\/en\/wp-json\/wp\/v2\/localizaciones\/localizacion\/11550","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/spainfilmcommission.com\/en\/wp-json\/wp\/v2\/localizaciones\/localizacion"}],"about":[{"href":"https:\/\/spainfilmcommission.com\/en\/wp-json\/wp\/v2\/types\/localizacion"}],"author":[{"embeddable":true,"href":"https:\/\/spainfilmcommission.com\/en\/wp-json\/wp\/v2\/users\/2"}],"wp:attachment":[{"href":"https:\/\/spainfilmcommission.com\/en\/wp-json\/wp\/v2\/media?parent=11550"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}