{"id":11544,"date":"2025-02-27T18:37:19","date_gmt":"2025-02-27T17:37:19","guid":{"rendered":"https:\/\/spainfilmcommission.com\/?post_type=localizacion&#038;p=11544"},"modified":"2025-04-21T13:37:33","modified_gmt":"2025-04-21T11:37:33","slug":"viaducto-de-villora-puente-de-los-imposibles","status":"publish","type":"localizacion","link":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/viaducto-de-villora-puente-de-los-imposibles\/","title":{"rendered":"Viaducto de Villora Puente de los imposibles"},"content":{"rendered":"","protected":false},"author":2,"template":"","meta":[],"class_list":["post-11544","localizacion","type-localizacion","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rodar en Viaducto de Villora Puente de los imposibles - Spain Film Commission<\/title>\n<meta name=\"description\" content=\"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Viaducto de Villora Puente de los imposibles\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/spainfilmcommission.com\/en\/ai-locations\/viaducto-de-villora-puente-de-los-imposibles\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rodar en Viaducto de Villora Puente de los imposibles - Spain Film Commission\" \/>\n<meta property=\"og:description\" content=\"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Viaducto de Villora Puente de los imposibles\" \/>\n<meta property=\"og:url\" content=\"https:\/\/spainfilmcommission.com\/en\/ai-locations\/viaducto-de-villora-puente-de-los-imposibles\/\" \/>\n<meta property=\"og:site_name\" content=\"Spain Film Commission\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-21T11:37:33+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/ai-locations\\\/viaducto-de-villora-puente-de-los-imposibles\\\/\",\"url\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/ai-locations\\\/viaducto-de-villora-puente-de-los-imposibles\\\/\",\"name\":\"Rodar en Viaducto de Villora Puente de los imposibles - Spain Film Commission\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#website\"},\"datePublished\":\"2025-02-27T17:37:19+00:00\",\"dateModified\":\"2025-04-21T11:37:33+00:00\",\"description\":\"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Viaducto de Villora Puente de los imposibles\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/ai-locations\\\/viaducto-de-villora-puente-de-los-imposibles\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/ai-locations\\\/viaducto-de-villora-puente-de-los-imposibles\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/ai-locations\\\/viaducto-de-villora-puente-de-los-imposibles\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Viaducto de Villora Puente de los imposibles\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/\",\"name\":\"Spain Film Commission\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#organization\",\"name\":\"Spain Film Commission\",\"url\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/spainfilmcommission.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/SPC_COLOR.png\",\"contentUrl\":\"https:\\\/\\\/spainfilmcommission.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/SPC_COLOR.png\",\"width\":1665,\"height\":1665,\"caption\":\"Spain Film Commission\"},\"image\":{\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rodar en Viaducto de Villora Puente de los imposibles - Spain Film Commission","description":"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Viaducto de Villora Puente de los imposibles","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/viaducto-de-villora-puente-de-los-imposibles\/","og_locale":"en_US","og_type":"article","og_title":"Rodar en Viaducto de Villora Puente de los imposibles - Spain Film Commission","og_description":"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Viaducto de Villora Puente de los imposibles","og_url":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/viaducto-de-villora-puente-de-los-imposibles\/","og_site_name":"Spain Film Commission","article_modified_time":"2025-04-21T11:37:33+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/viaducto-de-villora-puente-de-los-imposibles\/","url":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/viaducto-de-villora-puente-de-los-imposibles\/","name":"Rodar en Viaducto de Villora Puente de los imposibles - Spain Film Commission","isPartOf":{"@id":"https:\/\/spainfilmcommission.com\/en\/#website"},"datePublished":"2025-02-27T17:37:19+00:00","dateModified":"2025-04-21T11:37:33+00:00","description":"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Viaducto de Villora Puente de los imposibles","breadcrumb":{"@id":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/viaducto-de-villora-puente-de-los-imposibles\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/spainfilmcommission.com\/en\/ai-locations\/viaducto-de-villora-puente-de-los-imposibles\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/viaducto-de-villora-puente-de-los-imposibles\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/spainfilmcommission.com\/en\/"},{"@type":"ListItem","position":2,"name":"Viaducto de Villora Puente de los imposibles"}]},{"@type":"WebSite","@id":"https:\/\/spainfilmcommission.com\/en\/#website","url":"https:\/\/spainfilmcommission.com\/en\/","name":"Spain Film Commission","description":"","publisher":{"@id":"https:\/\/spainfilmcommission.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/spainfilmcommission.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/spainfilmcommission.com\/en\/#organization","name":"Spain Film Commission","url":"https:\/\/spainfilmcommission.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/spainfilmcommission.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2024\/07\/SPC_COLOR.png","contentUrl":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2024\/07\/SPC_COLOR.png","width":1665,"height":1665,"caption":"Spain Film Commission"},"image":{"@id":"https:\/\/spainfilmcommission.com\/en\/#\/schema\/logo\/image\/"}}]}},"socio":[{"ID":"54","user_login":"castilla-la-mancha-film-commission","user_nicename":"castilla-la-mancha-film-commission","display_name":"castilla-la-mancha-film-commission","user_pass":"****************","user_email":"info@castillalamanchafilm.com","user_url":"","user_registered":"2024-12-19 18:53:18","id":54}],"nombrees":"Viaducto de Villora, Puente de los imposibles","nombreen":"Viaducto de Villora, Puente de los imposibles","localidad":"Villora","provincia":"Cuenca","coordenadas_maps":"39.712622, -1.485919","latitud":"39.712622000000","longitud":"-1.485919000000","direcciones":"","direccionen":"","cod_postal":[],"telefono":"","fax":"","mail":"","web":"http:\/\/www.castillalamanchafilm.com\/menu\/localizaciones\/id27-viaducto-de-villora.html","descripciones":"En el l\u00edmite de la Serran\u00eda de Cuenca, en el t\u00e9rmino municipal de Villora, se encuentra el denominado\u00a0Puente de los Imposibles,\u00a0sobrenombrado as\u00ed por la gran dificultad que supuso su construcci\u00f3n para salvar el r\u00edo Villora. Es parte de la l\u00ednea ferroviaria Madrid-Valencia, cuya orograf\u00eda en este tramo es especialmente quebrada y exigi\u00f3 la construcci\u00f3n de importantes puentes de largu\u00edsimos pilares. Construido en hormig\u00f3n, de 274 metros de longitud p...","descripcionen":"In the limit of the Serran\u00eda de Cuenca, in the municipality of Villora, there is the so-called Puente de los Imposibles (Bridge of the Impossible), so named because of the great difficulty involved in its construction to save the Villora River. It is part of the Madrid-Valencia railway line, whose orography in this section is especially broken and required the construction of important bridges of very long pillars. Built in concrete, 274 meters long by 67 meters high, 4 arches of 16 meters, 4 more than 30 meters in the tallest columns and three more than another 16 meters. After the construction of the line after the Spanish Civil War, in 1942, it was one of the great inaugur...","galeria":[{"ID":"16257","post_author":"2","post_date":"2025-03-07 23:47:37","post_date_gmt":"2025-03-07 22:47:37","post_content":"","post_title":"foto-504_3625","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"foto-504_3625","to_ping":"","pinged":"","post_modified":"2025-04-21 13:37:33","post_modified_gmt":"2025-04-21 11:37:33","post_content_filtered":"","post_parent":"11544","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/foto-504_3625.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"16257"},{"ID":"16259","post_author":"2","post_date":"2025-03-07 23:47:40","post_date_gmt":"2025-03-07 22:47:40","post_content":"","post_title":"foto-504_3626","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"foto-504_3626","to_ping":"","pinged":"","post_modified":"2025-04-21 13:37:33","post_modified_gmt":"2025-04-21 11:37:33","post_content_filtered":"","post_parent":"11544","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/foto-504_3626.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"16259"},{"ID":"16261","post_author":"2","post_date":"2025-03-07 23:47:43","post_date_gmt":"2025-03-07 22:47:43","post_content":"","post_title":"foto-504_3627","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"foto-504_3627","to_ping":"","pinged":"","post_modified":"2025-04-21 13:37:33","post_modified_gmt":"2025-04-21 11:37:33","post_content_filtered":"","post_parent":"11544","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/foto-504_3627.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"16261"}],"nombrepaginaes":"viaducto-de-villora-puente-de-los-imposibles","nombrepaginaen":"viaducto-de-villora-puente-de-los-imposibles","latitud_gps":"","longitud_gps":"","adicionaleses":"","adicionalesen":"","videoes":"","videoen":"","video2es":"","video2en":"","_links":{"self":[{"href":"https:\/\/spainfilmcommission.com\/en\/wp-json\/wp\/v2\/localizaciones\/localizacion\/11544","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/spainfilmcommission.com\/en\/wp-json\/wp\/v2\/localizaciones\/localizacion"}],"about":[{"href":"https:\/\/spainfilmcommission.com\/en\/wp-json\/wp\/v2\/types\/localizacion"}],"author":[{"embeddable":true,"href":"https:\/\/spainfilmcommission.com\/en\/wp-json\/wp\/v2\/users\/2"}],"wp:attachment":[{"href":"https:\/\/spainfilmcommission.com\/en\/wp-json\/wp\/v2\/media?parent=11544"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}