{"id":11543,"date":"2025-02-27T18:34:46","date_gmt":"2025-02-27T17:34:46","guid":{"rendered":"https:\/\/spainfilmcommission.com\/?post_type=localizacion&#038;p=11543"},"modified":"2025-04-22T08:34:16","modified_gmt":"2025-04-22T06:34:16","slug":"monasterio-de-ucles","status":"publish","type":"localizacion","link":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/monasterio-de-ucles\/","title":{"rendered":"Monasterio de Ucl\u00e9s"},"content":{"rendered":"","protected":false},"author":2,"template":"","meta":[],"class_list":["post-11543","localizacion","type-localizacion","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rodar en Monasterio de Ucl\u00e9s - Spain Film Commission<\/title>\n<meta name=\"description\" content=\"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Monasterio de Ucl\u00e9s\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/spainfilmcommission.com\/en\/ai-locations\/monasterio-de-ucles\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rodar en Monasterio de Ucl\u00e9s - Spain Film Commission\" \/>\n<meta property=\"og:description\" content=\"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Monasterio de Ucl\u00e9s\" \/>\n<meta property=\"og:url\" content=\"https:\/\/spainfilmcommission.com\/en\/ai-locations\/monasterio-de-ucles\/\" \/>\n<meta property=\"og:site_name\" content=\"Spain Film Commission\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-22T06:34:16+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/ai-locations\\\/monasterio-de-ucles\\\/\",\"url\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/ai-locations\\\/monasterio-de-ucles\\\/\",\"name\":\"Rodar en Monasterio de Ucl\u00e9s - Spain Film Commission\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#website\"},\"datePublished\":\"2025-02-27T17:34:46+00:00\",\"dateModified\":\"2025-04-22T06:34:16+00:00\",\"description\":\"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Monasterio de Ucl\u00e9s\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/ai-locations\\\/monasterio-de-ucles\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/ai-locations\\\/monasterio-de-ucles\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/ai-locations\\\/monasterio-de-ucles\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Monasterio de Ucl\u00e9s\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/\",\"name\":\"Spain Film Commission\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#organization\",\"name\":\"Spain Film Commission\",\"url\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/spainfilmcommission.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/SPC_COLOR.png\",\"contentUrl\":\"https:\\\/\\\/spainfilmcommission.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/SPC_COLOR.png\",\"width\":1665,\"height\":1665,\"caption\":\"Spain Film Commission\"},\"image\":{\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rodar en Monasterio de Ucl\u00e9s - Spain Film Commission","description":"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Monasterio de Ucl\u00e9s","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/monasterio-de-ucles\/","og_locale":"en_US","og_type":"article","og_title":"Rodar en Monasterio de Ucl\u00e9s - Spain Film Commission","og_description":"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Monasterio de Ucl\u00e9s","og_url":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/monasterio-de-ucles\/","og_site_name":"Spain Film Commission","article_modified_time":"2025-04-22T06:34:16+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/monasterio-de-ucles\/","url":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/monasterio-de-ucles\/","name":"Rodar en Monasterio de Ucl\u00e9s - Spain Film Commission","isPartOf":{"@id":"https:\/\/spainfilmcommission.com\/en\/#website"},"datePublished":"2025-02-27T17:34:46+00:00","dateModified":"2025-04-22T06:34:16+00:00","description":"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Monasterio de Ucl\u00e9s","breadcrumb":{"@id":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/monasterio-de-ucles\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/spainfilmcommission.com\/en\/ai-locations\/monasterio-de-ucles\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/monasterio-de-ucles\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/spainfilmcommission.com\/en\/"},{"@type":"ListItem","position":2,"name":"Monasterio de Ucl\u00e9s"}]},{"@type":"WebSite","@id":"https:\/\/spainfilmcommission.com\/en\/#website","url":"https:\/\/spainfilmcommission.com\/en\/","name":"Spain Film Commission","description":"","publisher":{"@id":"https:\/\/spainfilmcommission.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/spainfilmcommission.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/spainfilmcommission.com\/en\/#organization","name":"Spain Film Commission","url":"https:\/\/spainfilmcommission.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/spainfilmcommission.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2024\/07\/SPC_COLOR.png","contentUrl":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2024\/07\/SPC_COLOR.png","width":1665,"height":1665,"caption":"Spain Film Commission"},"image":{"@id":"https:\/\/spainfilmcommission.com\/en\/#\/schema\/logo\/image\/"}}]}},"socio":[{"ID":"54","user_login":"castilla-la-mancha-film-commission","user_nicename":"castilla-la-mancha-film-commission","display_name":"castilla-la-mancha-film-commission","user_pass":"****************","user_email":"info@castillalamanchafilm.com","user_url":"","user_registered":"2024-12-19 18:53:18","id":54}],"nombrees":"Monasterio de Ucl\u00e9s","nombreen":"Monasterio de Ucl\u00e9s","localidad":"Ucl\u00e9s","provincia":"Cuenca","coordenadas_maps":"39.980649, -2.863174","latitud":"39.980649000000","longitud":"-2.863174000000","direcciones":"","direccionen":"","cod_postal":[],"telefono":"","fax":"","mail":"","web":"http:\/\/www.castillalamanchafilm.com\/menu\/localizaciones\/id21-monasterio-de-ucles.html","descripciones":"El Monasterio de Ucl\u00e9s, El Escorial de La Mancha, es de planta cuadrada con patio central y claustro de dos alturas, nueve diez vanos por cada lado, pilastras de planta cuadrada y arcos de medio punto; el deambulatorio est\u00e1 cubierto con una b\u00f3veda de ca\u00f1\u00f3n con lunetos y los arcos formeros, resaltados en piedra, sujetan el piso superior, resuelto con huecos adintelados, que siguen el mismo ritmo de la planta inferior decorados con motivos vegetales baquet\u00f3n y rejer\u00eda; en el centro del patio hay un aljibe en piedra caliza y decoraci\u00f3n barroca, con una gran tarja del escudo real.","descripcionen":"The Ucl\u00e9s Monastery, El Escorial de La Mancha, has a square floor plan with a central patio and two-level cloister, nine ten openings on each side, pilasters with a square floor plan and half-point arches; the ambulatory is covered with a barrel vault with lunettes and the arches formeros, highlighted in stone, hold the upper floor, resolved with lintelled gaps, which follow the same rhythm of the lower floor decorated with vegetal motifs, baquet\u00f3n and rejer\u00eda; In the center of the patio there is a cistern in limestone and baroque decoration, with a large tarja of the royal shield.","galeria":[{"ID":"16237","post_author":"2","post_date":"2025-03-07 23:47:18","post_date_gmt":"2025-03-07 22:47:18","post_content":"","post_title":"foto-503_3615","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"foto-503_3615","to_ping":"","pinged":"","post_modified":"2025-04-22 08:34:16","post_modified_gmt":"2025-04-22 06:34:16","post_content_filtered":"","post_parent":"11543","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/foto-503_3615.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"16237"},{"ID":"16239","post_author":"2","post_date":"2025-03-07 23:47:20","post_date_gmt":"2025-03-07 22:47:20","post_content":"","post_title":"foto-503_3616","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"foto-503_3616","to_ping":"","pinged":"","post_modified":"2025-04-22 08:34:16","post_modified_gmt":"2025-04-22 06:34:16","post_content_filtered":"","post_parent":"11543","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/foto-503_3616.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"16239"},{"ID":"16241","post_author":"2","post_date":"2025-03-07 23:47:22","post_date_gmt":"2025-03-07 22:47:22","post_content":"","post_title":"foto-503_3617","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"foto-503_3617","to_ping":"","pinged":"","post_modified":"2025-04-22 08:34:16","post_modified_gmt":"2025-04-22 06:34:16","post_content_filtered":"","post_parent":"11543","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/foto-503_3617.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"16241"},{"ID":"16243","post_author":"2","post_date":"2025-03-07 23:47:24","post_date_gmt":"2025-03-07 22:47:24","post_content":"","post_title":"foto-503_3618","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"foto-503_3618","to_ping":"","pinged":"","post_modified":"2025-04-22 08:34:16","post_modified_gmt":"2025-04-22 06:34:16","post_content_filtered":"","post_parent":"11543","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/foto-503_3618.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"16243"},{"ID":"16245","post_author":"2","post_date":"2025-03-07 23:47:26","post_date_gmt":"2025-03-07 22:47:26","post_content":"","post_title":"foto-503_3619","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"foto-503_3619","to_ping":"","pinged":"","post_modified":"2025-04-22 08:34:16","post_modified_gmt":"2025-04-22 06:34:16","post_content_filtered":"","post_parent":"11543","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/foto-503_3619.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"16245"},{"ID":"16247","post_author":"2","post_date":"2025-03-07 23:47:28","post_date_gmt":"2025-03-07 22:47:28","post_content":"","post_title":"foto-503_3620","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"foto-503_3620","to_ping":"","pinged":"","post_modified":"2025-04-22 08:34:16","post_modified_gmt":"2025-04-22 06:34:16","post_content_filtered":"","post_parent":"11543","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/foto-503_3620.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"16247"},{"ID":"16249","post_author":"2","post_date":"2025-03-07 23:47:29","post_date_gmt":"2025-03-07 22:47:29","post_content":"","post_title":"foto-503_3621","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"foto-503_3621","to_ping":"","pinged":"","post_modified":"2025-04-22 08:34:16","post_modified_gmt":"2025-04-22 06:34:16","post_content_filtered":"","post_parent":"11543","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/foto-503_3621.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"16249"},{"ID":"16251","post_author":"2","post_date":"2025-03-07 23:47:31","post_date_gmt":"2025-03-07 22:47:31","post_content":"","post_title":"foto-503_3622","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"foto-503_3622","to_ping":"","pinged":"","post_modified":"2025-04-22 08:34:16","post_modified_gmt":"2025-04-22 06:34:16","post_content_filtered":"","post_parent":"11543","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/foto-503_3622.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"16251"},{"ID":"16253","post_author":"2","post_date":"2025-03-07 23:47:33","post_date_gmt":"2025-03-07 22:47:33","post_content":"","post_title":"foto-503_3623","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"foto-503_3623","to_ping":"","pinged":"","post_modified":"2025-04-22 08:34:16","post_modified_gmt":"2025-04-22 06:34:16","post_content_filtered":"","post_parent":"11543","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/foto-503_3623.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"16253"},{"ID":"16255","post_author":"2","post_date":"2025-03-07 23:47:35","post_date_gmt":"2025-03-07 22:47:35","post_content":"","post_title":"foto-503_3624","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"foto-503_3624","to_ping":"","pinged":"","post_modified":"2025-04-22 08:34:16","post_modified_gmt":"2025-04-22 06:34:16","post_content_filtered":"","post_parent":"11543","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/foto-503_3624.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"16255"}],"nombrepaginaes":"monasterio-de-ucles","nombrepaginaen":"monasterio-de-ucles","latitud_gps":"","longitud_gps":"","adicionaleses":"","adicionalesen":"","videoes":"","videoen":"","video2es":"","video2en":"","_links":{"self":[{"href":"https:\/\/spainfilmcommission.com\/en\/wp-json\/wp\/v2\/localizaciones\/localizacion\/11543","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/spainfilmcommission.com\/en\/wp-json\/wp\/v2\/localizaciones\/localizacion"}],"about":[{"href":"https:\/\/spainfilmcommission.com\/en\/wp-json\/wp\/v2\/types\/localizacion"}],"author":[{"embeddable":true,"href":"https:\/\/spainfilmcommission.com\/en\/wp-json\/wp\/v2\/users\/2"}],"wp:attachment":[{"href":"https:\/\/spainfilmcommission.com\/en\/wp-json\/wp\/v2\/media?parent=11543"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}