{"id":11265,"date":"2025-02-27T17:40:53","date_gmt":"2025-02-27T16:40:53","guid":{"rendered":"https:\/\/spainfilmcommission.com\/?post_type=localizacion&#038;p=11265"},"modified":"2025-04-21T13:50:57","modified_gmt":"2025-04-21T11:50:57","slug":"plaza-del-ayuntamiento-de-toledo","status":"publish","type":"localizacion","link":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/plaza-del-ayuntamiento-de-toledo\/","title":{"rendered":"Plaza del Ayuntamiento de Toledo"},"content":{"rendered":"","protected":false},"author":2,"template":"","meta":[],"class_list":["post-11265","localizacion","type-localizacion","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rodar en Plaza del Ayuntamiento de Toledo - Spain Film Commission<\/title>\n<meta name=\"description\" content=\"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Plaza del Ayuntamiento de Toledo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/spainfilmcommission.com\/en\/ai-locations\/plaza-del-ayuntamiento-de-toledo\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rodar en Plaza del Ayuntamiento de Toledo - Spain Film Commission\" \/>\n<meta property=\"og:description\" content=\"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Plaza del Ayuntamiento de Toledo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/spainfilmcommission.com\/en\/ai-locations\/plaza-del-ayuntamiento-de-toledo\/\" \/>\n<meta property=\"og:site_name\" content=\"Spain Film Commission\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-21T11:50:57+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/ai-locations\\\/plaza-del-ayuntamiento-de-toledo\\\/\",\"url\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/ai-locations\\\/plaza-del-ayuntamiento-de-toledo\\\/\",\"name\":\"Rodar en Plaza del Ayuntamiento de Toledo - Spain Film Commission\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#website\"},\"datePublished\":\"2025-02-27T16:40:53+00:00\",\"dateModified\":\"2025-04-21T11:50:57+00:00\",\"description\":\"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Plaza del Ayuntamiento de Toledo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/ai-locations\\\/plaza-del-ayuntamiento-de-toledo\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/ai-locations\\\/plaza-del-ayuntamiento-de-toledo\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/ai-locations\\\/plaza-del-ayuntamiento-de-toledo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Plaza del Ayuntamiento de Toledo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/\",\"name\":\"Spain Film Commission\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#organization\",\"name\":\"Spain Film Commission\",\"url\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/spainfilmcommission.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/SPC_COLOR.png\",\"contentUrl\":\"https:\\\/\\\/spainfilmcommission.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/SPC_COLOR.png\",\"width\":1665,\"height\":1665,\"caption\":\"Spain Film Commission\"},\"image\":{\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rodar en Plaza del Ayuntamiento de Toledo - Spain Film Commission","description":"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Plaza del Ayuntamiento de Toledo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/plaza-del-ayuntamiento-de-toledo\/","og_locale":"en_US","og_type":"article","og_title":"Rodar en Plaza del Ayuntamiento de Toledo - Spain Film Commission","og_description":"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Plaza del Ayuntamiento de Toledo","og_url":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/plaza-del-ayuntamiento-de-toledo\/","og_site_name":"Spain Film Commission","article_modified_time":"2025-04-21T11:50:57+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/plaza-del-ayuntamiento-de-toledo\/","url":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/plaza-del-ayuntamiento-de-toledo\/","name":"Rodar en Plaza del Ayuntamiento de Toledo - Spain Film Commission","isPartOf":{"@id":"https:\/\/spainfilmcommission.com\/en\/#website"},"datePublished":"2025-02-27T16:40:53+00:00","dateModified":"2025-04-21T11:50:57+00:00","description":"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Plaza del Ayuntamiento de Toledo","breadcrumb":{"@id":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/plaza-del-ayuntamiento-de-toledo\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/spainfilmcommission.com\/en\/ai-locations\/plaza-del-ayuntamiento-de-toledo\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/plaza-del-ayuntamiento-de-toledo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/spainfilmcommission.com\/en\/"},{"@type":"ListItem","position":2,"name":"Plaza del Ayuntamiento de Toledo"}]},{"@type":"WebSite","@id":"https:\/\/spainfilmcommission.com\/en\/#website","url":"https:\/\/spainfilmcommission.com\/en\/","name":"Spain Film Commission","description":"","publisher":{"@id":"https:\/\/spainfilmcommission.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/spainfilmcommission.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/spainfilmcommission.com\/en\/#organization","name":"Spain Film Commission","url":"https:\/\/spainfilmcommission.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/spainfilmcommission.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2024\/07\/SPC_COLOR.png","contentUrl":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2024\/07\/SPC_COLOR.png","width":1665,"height":1665,"caption":"Spain Film Commission"},"image":{"@id":"https:\/\/spainfilmcommission.com\/en\/#\/schema\/logo\/image\/"}}]}},"socio":[{"ID":"54","user_login":"castilla-la-mancha-film-commission","user_nicename":"castilla-la-mancha-film-commission","display_name":"castilla-la-mancha-film-commission","user_pass":"****************","user_email":"info@castillalamanchafilm.com","user_url":"","user_registered":"2024-12-19 18:53:18","id":54}],"nombrees":"Plaza del Ayuntamiento de Toledo","nombreen":"Plaza del Ayuntamiento de Toledo","localidad":"Toledo","provincia":"Toledo","coordenadas_maps":"39.8571, -4.02496","latitud":"39.857100000000","longitud":"-4.024960000000","direcciones":"Plaza Ayuntamiento","direccionen":"Plaza Ayuntamiento","cod_postal":"45002","telefono":"(+34) 925","fax":"","mail":"alazaro@jccm.es","web":"","descripciones":"Esta plaza contiene dos de los palacios m\u00e1s relevantes de Toledo (Castilla-La Mancha) y est\u00e1 coronada por la majestuosa y \u00fanica torre de la Catedral de Santa Mar\u00eda. A\u00fana el poder pol\u00edtico (Ayuntamiento, edificio herreriano), el religioso con la Catedral (\u00f3pera magna del G\u00f3tico espa\u00f1ol) y el Palacio Arzobispal (renacentista), unidos por el Arco de Palacio, y el judicial con el palacio de Justicia. Una escultura\/estanque de la prestigiosa artista Cristina Iglesias vino a enriquecerla en el a\u00f1o Greco.","descripcionen":"In this square we find two of Toledo's (Castile-La Mancha) most important palaces and the regal and maginificent tower of the Santa Mar\u00eda Cathedral. It combines the political power, represented by the Town Hall (Herrera building) with the religious power, represented by the Cathedral (Spanish Gothic masterpiece) and the Archbishop's Palace (Renaissance), joined by the Palace Arc; as well as the judiciary power with the Palace of Justice. A sculpture-pond by prestigious artist Cristina Iglesias came to enrich it during the Greco's centenary (2014).","galeria":[{"ID":"31011","post_author":"2","post_date":"2025-03-08 13:41:24","post_date_gmt":"2025-03-08 12:41:24","post_content":"","post_title":"plaza-del-ayuntamiento,-toledo_186_1","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"plaza-del-ayuntamiento-toledo_186_1","to_ping":"","pinged":"","post_modified":"2025-04-21 13:50:57","post_modified_gmt":"2025-04-21 11:50:57","post_content_filtered":"","post_parent":"11265","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/plaza-del-ayuntamiento-toledo_186_1.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"31011"},{"ID":"31013","post_author":"2","post_date":"2025-03-08 13:41:26","post_date_gmt":"2025-03-08 12:41:26","post_content":"","post_title":"plaza-del-ayuntamiento,-toledo_186_2","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"plaza-del-ayuntamiento-toledo_186_2","to_ping":"","pinged":"","post_modified":"2025-04-21 13:50:57","post_modified_gmt":"2025-04-21 11:50:57","post_content_filtered":"","post_parent":"11265","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/plaza-del-ayuntamiento-toledo_186_2.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"31013"},{"ID":"31015","post_author":"2","post_date":"2025-03-08 13:41:28","post_date_gmt":"2025-03-08 12:41:28","post_content":"","post_title":"plaza-del-ayuntamiento,-toledo_186_3","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"plaza-del-ayuntamiento-toledo_186_3","to_ping":"","pinged":"","post_modified":"2025-04-21 13:50:57","post_modified_gmt":"2025-04-21 11:50:57","post_content_filtered":"","post_parent":"11265","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/plaza-del-ayuntamiento-toledo_186_3.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"31015"},{"ID":"31017","post_author":"2","post_date":"2025-03-08 13:41:30","post_date_gmt":"2025-03-08 12:41:30","post_content":"","post_title":"plaza-del-ayuntamiento,-toledo_186_4","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"plaza-del-ayuntamiento-toledo_186_4","to_ping":"","pinged":"","post_modified":"2025-04-21 13:50:57","post_modified_gmt":"2025-04-21 11:50:57","post_content_filtered":"","post_parent":"11265","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/plaza-del-ayuntamiento-toledo_186_4.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"31017"},{"ID":"31019","post_author":"2","post_date":"2025-03-08 13:41:33","post_date_gmt":"2025-03-08 12:41:33","post_content":"","post_title":"plaza-del-ayuntamiento,-toledo_186_5","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"plaza-del-ayuntamiento-toledo_186_5","to_ping":"","pinged":"","post_modified":"2025-04-21 13:50:57","post_modified_gmt":"2025-04-21 11:50:57","post_content_filtered":"","post_parent":"11265","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/plaza-del-ayuntamiento-toledo_186_5.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"31019"},{"ID":"31021","post_author":"2","post_date":"2025-03-08 13:41:35","post_date_gmt":"2025-03-08 12:41:35","post_content":"","post_title":"plaza-del-ayuntamiento,-toledo_186_6","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"plaza-del-ayuntamiento-toledo_186_6","to_ping":"","pinged":"","post_modified":"2025-04-21 13:50:57","post_modified_gmt":"2025-04-21 11:50:57","post_content_filtered":"","post_parent":"11265","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/plaza-del-ayuntamiento-toledo_186_6.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"31021"},{"ID":"31023","post_author":"2","post_date":"2025-03-08 13:41:37","post_date_gmt":"2025-03-08 12:41:37","post_content":"","post_title":"plaza-del-ayuntamiento,-toledo_186_7","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"plaza-del-ayuntamiento-toledo_186_7","to_ping":"","pinged":"","post_modified":"2025-04-21 13:50:57","post_modified_gmt":"2025-04-21 11:50:57","post_content_filtered":"","post_parent":"11265","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/plaza-del-ayuntamiento-toledo_186_7.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"31023"},{"ID":"31025","post_author":"2","post_date":"2025-03-08 13:41:39","post_date_gmt":"2025-03-08 12:41:39","post_content":"","post_title":"plaza-del-ayuntamiento,-toledo_186_8","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"plaza-del-ayuntamiento-toledo_186_8","to_ping":"","pinged":"","post_modified":"2025-04-21 13:50:57","post_modified_gmt":"2025-04-21 11:50:57","post_content_filtered":"","post_parent":"11265","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/plaza-del-ayuntamiento-toledo_186_8.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"31025"}],"nombrepaginaes":"plaza-del-ayuntamiento-de-toledo","nombrepaginaen":"plaza-del-ayuntamiento-de-toledo","latitud_gps":"","longitud_gps":"","adicionaleses":"","adicionalesen":"","videoes":"","videoen":"","video2es":"","video2en":"","_links":{"self":[{"href":"https:\/\/spainfilmcommission.com\/en\/wp-json\/wp\/v2\/localizaciones\/localizacion\/11265","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/spainfilmcommission.com\/en\/wp-json\/wp\/v2\/localizaciones\/localizacion"}],"about":[{"href":"https:\/\/spainfilmcommission.com\/en\/wp-json\/wp\/v2\/types\/localizacion"}],"author":[{"embeddable":true,"href":"https:\/\/spainfilmcommission.com\/en\/wp-json\/wp\/v2\/users\/2"}],"wp:attachment":[{"href":"https:\/\/spainfilmcommission.com\/en\/wp-json\/wp\/v2\/media?parent=11265"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}