{"id":11258,"date":"2025-02-27T17:40:53","date_gmt":"2025-02-27T16:40:53","guid":{"rendered":"https:\/\/spainfilmcommission.com\/?post_type=localizacion&#038;p=11258"},"modified":"2025-04-21T19:13:30","modified_gmt":"2025-04-21T17:13:30","slug":"casas-bioclimaticas-iter","status":"publish","type":"localizacion","link":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/casas-bioclimaticas-iter\/","title":{"rendered":"Casas bioclim\u00e1ticas ITER"},"content":{"rendered":"","protected":false},"author":2,"template":"","meta":[],"class_list":["post-11258","localizacion","type-localizacion","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rodar en Casas bioclim\u00e1ticas ITER - Spain Film Commission<\/title>\n<meta name=\"description\" content=\"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Casas bioclim\u00e1ticas ITER\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/spainfilmcommission.com\/en\/ai-locations\/casas-bioclimaticas-iter\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rodar en Casas bioclim\u00e1ticas ITER - Spain Film Commission\" \/>\n<meta property=\"og:description\" content=\"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Casas bioclim\u00e1ticas ITER\" \/>\n<meta property=\"og:url\" content=\"https:\/\/spainfilmcommission.com\/en\/ai-locations\/casas-bioclimaticas-iter\/\" \/>\n<meta property=\"og:site_name\" content=\"Spain Film Commission\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-21T17:13:30+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/ai-locations\\\/casas-bioclimaticas-iter\\\/\",\"url\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/ai-locations\\\/casas-bioclimaticas-iter\\\/\",\"name\":\"Rodar en Casas bioclim\u00e1ticas ITER - Spain Film Commission\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#website\"},\"datePublished\":\"2025-02-27T16:40:53+00:00\",\"dateModified\":\"2025-04-21T17:13:30+00:00\",\"description\":\"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Casas bioclim\u00e1ticas ITER\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/ai-locations\\\/casas-bioclimaticas-iter\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/ai-locations\\\/casas-bioclimaticas-iter\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/ai-locations\\\/casas-bioclimaticas-iter\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Casas bioclim\u00e1ticas ITER\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/\",\"name\":\"Spain Film Commission\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#organization\",\"name\":\"Spain Film Commission\",\"url\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/spainfilmcommission.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/SPC_COLOR.png\",\"contentUrl\":\"https:\\\/\\\/spainfilmcommission.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/SPC_COLOR.png\",\"width\":1665,\"height\":1665,\"caption\":\"Spain Film Commission\"},\"image\":{\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rodar en Casas bioclim\u00e1ticas ITER - Spain Film Commission","description":"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Casas bioclim\u00e1ticas ITER","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/casas-bioclimaticas-iter\/","og_locale":"en_US","og_type":"article","og_title":"Rodar en Casas bioclim\u00e1ticas ITER - Spain Film Commission","og_description":"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Casas bioclim\u00e1ticas ITER","og_url":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/casas-bioclimaticas-iter\/","og_site_name":"Spain Film Commission","article_modified_time":"2025-04-21T17:13:30+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/casas-bioclimaticas-iter\/","url":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/casas-bioclimaticas-iter\/","name":"Rodar en Casas bioclim\u00e1ticas ITER - Spain Film Commission","isPartOf":{"@id":"https:\/\/spainfilmcommission.com\/en\/#website"},"datePublished":"2025-02-27T16:40:53+00:00","dateModified":"2025-04-21T17:13:30+00:00","description":"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Casas bioclim\u00e1ticas ITER","breadcrumb":{"@id":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/casas-bioclimaticas-iter\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/spainfilmcommission.com\/en\/ai-locations\/casas-bioclimaticas-iter\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/casas-bioclimaticas-iter\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/spainfilmcommission.com\/en\/"},{"@type":"ListItem","position":2,"name":"Casas bioclim\u00e1ticas ITER"}]},{"@type":"WebSite","@id":"https:\/\/spainfilmcommission.com\/en\/#website","url":"https:\/\/spainfilmcommission.com\/en\/","name":"Spain Film Commission","description":"","publisher":{"@id":"https:\/\/spainfilmcommission.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/spainfilmcommission.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/spainfilmcommission.com\/en\/#organization","name":"Spain Film Commission","url":"https:\/\/spainfilmcommission.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/spainfilmcommission.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2024\/07\/SPC_COLOR.png","contentUrl":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2024\/07\/SPC_COLOR.png","width":1665,"height":1665,"caption":"Spain Film Commission"},"image":{"@id":"https:\/\/spainfilmcommission.com\/en\/#\/schema\/logo\/image\/"}}]}},"socio":[{"ID":"46","user_login":"canary-island-film","user_nicename":"canary-island-film","display_name":"canary-island-film","user_pass":"****************","user_email":"hello@canaryislandsfilm.com","user_url":"","user_registered":"2024-12-19 18:02:01","id":46}],"nombrees":"Casas bioclim\u00e1ticas ITER","nombreen":"Casas bioclim\u00e1ticas ITER","localidad":"Granadilla de Abona","provincia":"Santa Cruz de Tenerife","coordenadas_maps":"28.0679, -16.5091","latitud":"28.067900000000","longitud":"-16.509100000000","direcciones":"Casas bioclim\u00e1ticas, ITER, Granadilla de Abona","direccionen":"Casas bioclim\u00e1ticas, ITER, Granadilla de Abona","cod_postal":[],"telefono":"(+34) 647","fax":"","mail":"film@webtenerife.com","web":"http:\/\/www.webtenerife.com\/alojamiento\/casas-bioclimaticas\/","descripciones":"Son un conjunto de 24 viviendas \u00fanicas con enorme encanto en Granadilla de Abona (Santa Cruz de Tenerife, Canarias). La filosof\u00eda que gu\u00eda el proyecto es conseguir un grupo de casas autosuficientes con CO2 =0, que sirvan como modelo para el desarrollo de nuevas edificaciones. La arquitectura pasiva integra las energ\u00edas renovables. El proyecto est\u00e1 dirigido y avalado por el Instituto Tecnol\u00f3gico de Energias Renovables, se cre\u00f3 a partir de un concurso internacional.","descripcionen":"They are a set of 24 unique homes with great charm in Granadilla de Abona (Santa Cruz de Tenerife, Canary Islands). The philosophy that guides the project is to get a group of self-sufficient houses with 0 CO2, which serve as a model for the development of new buildings. The architecture of the houses integrates renewable energy. The project is managed and supported by the Technological Institute of Renewable Energy and was created the result of an international competition.","galeria":[{"ID":"13397","post_author":"2","post_date":"2025-03-07 22:45:30","post_date_gmt":"2025-03-07 21:45:30","post_content":"","post_title":"casas-bioclim\u00e1ticas-iter_178_1","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"casas-bioclimaticas-iter_178_1","to_ping":"","pinged":"","post_modified":"2025-04-21 19:13:31","post_modified_gmt":"2025-04-21 17:13:31","post_content_filtered":"","post_parent":"11258","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/casas-bioclimaticas-iter_178_1.gif","menu_order":"0","post_type":"attachment","post_mime_type":"image\/gif","comment_count":"0","pod_item_id":"13397"},{"ID":"13399","post_author":"2","post_date":"2025-03-07 22:45:33","post_date_gmt":"2025-03-07 21:45:33","post_content":"","post_title":"casas-bioclim\u00e1ticas-iter_178_2","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"casas-bioclimaticas-iter_178_2","to_ping":"","pinged":"","post_modified":"2025-04-21 19:13:31","post_modified_gmt":"2025-04-21 17:13:31","post_content_filtered":"","post_parent":"11258","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/casas-bioclimaticas-iter_178_2.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"13399"},{"ID":"13401","post_author":"2","post_date":"2025-03-07 22:45:35","post_date_gmt":"2025-03-07 21:45:35","post_content":"","post_title":"casas-bioclim\u00e1ticas-iter_178_3","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"casas-bioclimaticas-iter_178_3","to_ping":"","pinged":"","post_modified":"2025-04-21 19:13:31","post_modified_gmt":"2025-04-21 17:13:31","post_content_filtered":"","post_parent":"11258","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/casas-bioclimaticas-iter_178_3.gif","menu_order":"0","post_type":"attachment","post_mime_type":"image\/gif","comment_count":"0","pod_item_id":"13401"},{"ID":"13403","post_author":"2","post_date":"2025-03-07 22:45:38","post_date_gmt":"2025-03-07 21:45:38","post_content":"","post_title":"casas-bioclim\u00e1ticas-iter_178_4","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"casas-bioclimaticas-iter_178_4","to_ping":"","pinged":"","post_modified":"2025-04-21 19:13:31","post_modified_gmt":"2025-04-21 17:13:31","post_content_filtered":"","post_parent":"11258","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/casas-bioclimaticas-iter_178_4.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"13403"},{"ID":"13405","post_author":"2","post_date":"2025-03-07 22:45:39","post_date_gmt":"2025-03-07 21:45:39","post_content":"","post_title":"casas-bioclim\u00e1ticas-iter_178_5","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"casas-bioclimaticas-iter_178_5","to_ping":"","pinged":"","post_modified":"2025-04-21 19:13:31","post_modified_gmt":"2025-04-21 17:13:31","post_content_filtered":"","post_parent":"11258","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/casas-bioclimaticas-iter_178_5.gif","menu_order":"0","post_type":"attachment","post_mime_type":"image\/gif","comment_count":"0","pod_item_id":"13405"},{"ID":"13407","post_author":"2","post_date":"2025-03-07 22:45:42","post_date_gmt":"2025-03-07 21:45:42","post_content":"","post_title":"casas-bioclim\u00e1ticas-iter_178_6","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"casas-bioclimaticas-iter_178_6","to_ping":"","pinged":"","post_modified":"2025-04-21 19:13:31","post_modified_gmt":"2025-04-21 17:13:31","post_content_filtered":"","post_parent":"11258","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/casas-bioclimaticas-iter_178_6.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"13407"},{"ID":"13409","post_author":"2","post_date":"2025-03-07 22:45:44","post_date_gmt":"2025-03-07 21:45:44","post_content":"","post_title":"casas-bioclim\u00e1ticas-iter_178_7","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"casas-bioclimaticas-iter_178_7","to_ping":"","pinged":"","post_modified":"2025-04-21 19:13:31","post_modified_gmt":"2025-04-21 17:13:31","post_content_filtered":"","post_parent":"11258","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/casas-bioclimaticas-iter_178_7.gif","menu_order":"0","post_type":"attachment","post_mime_type":"image\/gif","comment_count":"0","pod_item_id":"13409"},{"ID":"13411","post_author":"2","post_date":"2025-03-07 22:45:47","post_date_gmt":"2025-03-07 21:45:47","post_content":"","post_title":"casas-bioclim\u00e1ticas-iter_178_8","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"casas-bioclimaticas-iter_178_8","to_ping":"","pinged":"","post_modified":"2025-04-21 19:13:31","post_modified_gmt":"2025-04-21 17:13:31","post_content_filtered":"","post_parent":"11258","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/casas-bioclimaticas-iter_178_8.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"13411"},{"ID":"13413","post_author":"2","post_date":"2025-03-07 22:45:49","post_date_gmt":"2025-03-07 21:45:49","post_content":"","post_title":"casas-bioclim\u00e1ticas-iter_178_9","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"casas-bioclimaticas-iter_178_9","to_ping":"","pinged":"","post_modified":"2025-04-21 19:13:31","post_modified_gmt":"2025-04-21 17:13:31","post_content_filtered":"","post_parent":"11258","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/casas-bioclimaticas-iter_178_9.gif","menu_order":"0","post_type":"attachment","post_mime_type":"image\/gif","comment_count":"0","pod_item_id":"13413"},{"ID":"13415","post_author":"2","post_date":"2025-03-07 22:45:52","post_date_gmt":"2025-03-07 21:45:52","post_content":"","post_title":"casas-bioclim\u00e1ticas-iter_178_10","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"casas-bioclimaticas-iter_178_10","to_ping":"","pinged":"","post_modified":"2025-04-21 19:13:31","post_modified_gmt":"2025-04-21 17:13:31","post_content_filtered":"","post_parent":"11258","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/casas-bioclimaticas-iter_178_10.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"13415"},{"ID":"13417","post_author":"2","post_date":"2025-03-07 22:45:54","post_date_gmt":"2025-03-07 21:45:54","post_content":"","post_title":"casas-bioclim\u00e1ticas-iter_178_11","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"casas-bioclimaticas-iter_178_11","to_ping":"","pinged":"","post_modified":"2025-04-21 19:13:31","post_modified_gmt":"2025-04-21 17:13:31","post_content_filtered":"","post_parent":"11258","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/casas-bioclimaticas-iter_178_11.gif","menu_order":"0","post_type":"attachment","post_mime_type":"image\/gif","comment_count":"0","pod_item_id":"13417"},{"ID":"13419","post_author":"2","post_date":"2025-03-07 22:45:56","post_date_gmt":"2025-03-07 21:45:56","post_content":"","post_title":"casas-bioclim\u00e1ticas-iter_178_12","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"casas-bioclimaticas-iter_178_12","to_ping":"","pinged":"","post_modified":"2025-04-21 19:13:31","post_modified_gmt":"2025-04-21 17:13:31","post_content_filtered":"","post_parent":"11258","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/casas-bioclimaticas-iter_178_12.gif","menu_order":"0","post_type":"attachment","post_mime_type":"image\/gif","comment_count":"0","pod_item_id":"13419"}],"nombrepaginaes":"casas-bioclimaticas-iter","nombrepaginaen":"casas-bioclimaticas-iter","latitud_gps":"","longitud_gps":"","adicionaleses":"","adicionalesen":"","videoes":"","videoen":"","video2es":"","video2en":"","_links":{"self":[{"href":"https:\/\/spainfilmcommission.com\/en\/wp-json\/wp\/v2\/localizaciones\/localizacion\/11258","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/spainfilmcommission.com\/en\/wp-json\/wp\/v2\/localizaciones\/localizacion"}],"about":[{"href":"https:\/\/spainfilmcommission.com\/en\/wp-json\/wp\/v2\/types\/localizacion"}],"author":[{"embeddable":true,"href":"https:\/\/spainfilmcommission.com\/en\/wp-json\/wp\/v2\/users\/2"}],"wp:attachment":[{"href":"https:\/\/spainfilmcommission.com\/en\/wp-json\/wp\/v2\/media?parent=11258"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}