{"id":11222,"date":"2025-02-27T17:31:23","date_gmt":"2025-02-27T16:31:23","guid":{"rendered":"https:\/\/spainfilmcommission.com\/?post_type=localizacion&#038;p=11222"},"modified":"2025-04-21T12:09:22","modified_gmt":"2025-04-21T10:09:22","slug":"puerta-de-cordoba","status":"publish","type":"localizacion","link":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/puerta-de-cordoba\/","title":{"rendered":"Puerta de C\u00f3rdoba"},"content":{"rendered":"","protected":false},"author":2,"template":"","meta":[],"class_list":["post-11222","localizacion","type-localizacion","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rodar en Puerta de C\u00f3rdoba - Spain Film Commission<\/title>\n<meta name=\"description\" content=\"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Puerta de C\u00f3rdoba\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/spainfilmcommission.com\/en\/ai-locations\/puerta-de-cordoba\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rodar en Puerta de C\u00f3rdoba - Spain Film Commission\" \/>\n<meta property=\"og:description\" content=\"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Puerta de C\u00f3rdoba\" \/>\n<meta property=\"og:url\" content=\"https:\/\/spainfilmcommission.com\/en\/ai-locations\/puerta-de-cordoba\/\" \/>\n<meta property=\"og:site_name\" content=\"Spain Film Commission\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-21T10:09:22+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/ai-locations\\\/puerta-de-cordoba\\\/\",\"url\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/ai-locations\\\/puerta-de-cordoba\\\/\",\"name\":\"Rodar en Puerta de C\u00f3rdoba - Spain Film Commission\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#website\"},\"datePublished\":\"2025-02-27T16:31:23+00:00\",\"dateModified\":\"2025-04-21T10:09:22+00:00\",\"description\":\"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Puerta de C\u00f3rdoba\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/ai-locations\\\/puerta-de-cordoba\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/ai-locations\\\/puerta-de-cordoba\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/ai-locations\\\/puerta-de-cordoba\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Puerta de C\u00f3rdoba\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/\",\"name\":\"Spain Film Commission\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#organization\",\"name\":\"Spain Film Commission\",\"url\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/spainfilmcommission.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/SPC_COLOR.png\",\"contentUrl\":\"https:\\\/\\\/spainfilmcommission.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/SPC_COLOR.png\",\"width\":1665,\"height\":1665,\"caption\":\"Spain Film Commission\"},\"image\":{\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rodar en Puerta de C\u00f3rdoba - Spain Film Commission","description":"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Puerta de C\u00f3rdoba","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/puerta-de-cordoba\/","og_locale":"en_US","og_type":"article","og_title":"Rodar en Puerta de C\u00f3rdoba - Spain Film Commission","og_description":"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Puerta de C\u00f3rdoba","og_url":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/puerta-de-cordoba\/","og_site_name":"Spain Film Commission","article_modified_time":"2025-04-21T10:09:22+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/puerta-de-cordoba\/","url":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/puerta-de-cordoba\/","name":"Rodar en Puerta de C\u00f3rdoba - Spain Film Commission","isPartOf":{"@id":"https:\/\/spainfilmcommission.com\/en\/#website"},"datePublished":"2025-02-27T16:31:23+00:00","dateModified":"2025-04-21T10:09:22+00:00","description":"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Puerta de C\u00f3rdoba","breadcrumb":{"@id":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/puerta-de-cordoba\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/spainfilmcommission.com\/en\/ai-locations\/puerta-de-cordoba\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/puerta-de-cordoba\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/spainfilmcommission.com\/en\/"},{"@type":"ListItem","position":2,"name":"Puerta de C\u00f3rdoba"}]},{"@type":"WebSite","@id":"https:\/\/spainfilmcommission.com\/en\/#website","url":"https:\/\/spainfilmcommission.com\/en\/","name":"Spain Film Commission","description":"","publisher":{"@id":"https:\/\/spainfilmcommission.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/spainfilmcommission.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/spainfilmcommission.com\/en\/#organization","name":"Spain Film Commission","url":"https:\/\/spainfilmcommission.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/spainfilmcommission.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2024\/07\/SPC_COLOR.png","contentUrl":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2024\/07\/SPC_COLOR.png","width":1665,"height":1665,"caption":"Spain Film Commission"},"image":{"@id":"https:\/\/spainfilmcommission.com\/en\/#\/schema\/logo\/image\/"}}]}},"socio":[{"ID":"38","user_login":"carmona-film-office","user_nicename":"carmona-film-office","display_name":"carmona-film-office","user_pass":"****************","user_email":"pmoreno@carmona.org","user_url":"","user_registered":"2024-12-19 16:40:55","id":38}],"nombrees":"Puerta de C\u00f3rdoba","nombreen":"Puerta de C\u00f3rdoba","localidad":"Carmona","provincia":"Sevilla","coordenadas_maps":"37.4764, -5.63354","latitud":"37.476400000000","longitud":"-5.633540000000","direcciones":"Dolores Quintanilla, s\/n","direccionen":"Dolores Quintanilla, s\/n","cod_postal":"41410","telefono":"","fax":"","mail":"","web":"http:\/\/www.sodecar.org\/plan_especial\/fichas\/edificios\/15.pdf","descripciones":"Situada en Carmona (Sevilla, Andaluc\u00eda), la Puerta de C\u00f3rdoba tiene a Oriente dos torreones, un arco romano, y dos puertas peatonales a ambos lados que cerraban la ciudad hacia la Corduba romana.","descripcionen":"Located in Carmona (Seville, Andalusia), the C\u00f3rdoba Gate has two towers, on the East, a Roman arch and two pedestrian doors on both sides that closed oriented to the Roman Corduba.","galeria":[{"ID":"14871","post_author":"2","post_date":"2025-03-07 23:22:12","post_date_gmt":"2025-03-07 22:22:12","post_content":"","post_title":"foto-139_4710","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"foto-139_4710","to_ping":"","pinged":"","post_modified":"2025-04-21 12:09:22","post_modified_gmt":"2025-04-21 10:09:22","post_content_filtered":"","post_parent":"11222","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/foto-139_4710.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"14871"},{"ID":"14873","post_author":"2","post_date":"2025-03-07 23:22:14","post_date_gmt":"2025-03-07 22:22:14","post_content":"","post_title":"foto-139_4711","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"foto-139_4711","to_ping":"","pinged":"","post_modified":"2025-04-21 12:09:22","post_modified_gmt":"2025-04-21 10:09:22","post_content_filtered":"","post_parent":"11222","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/foto-139_4711.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"14873"},{"ID":"14875","post_author":"2","post_date":"2025-03-07 23:22:16","post_date_gmt":"2025-03-07 22:22:16","post_content":"","post_title":"foto-139_4712","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"foto-139_4712","to_ping":"","pinged":"","post_modified":"2025-04-21 12:09:22","post_modified_gmt":"2025-04-21 10:09:22","post_content_filtered":"","post_parent":"11222","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/foto-139_4712.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"14875"},{"ID":"14877","post_author":"2","post_date":"2025-03-07 23:22:17","post_date_gmt":"2025-03-07 22:22:17","post_content":"","post_title":"foto-139_4713","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"foto-139_4713","to_ping":"","pinged":"","post_modified":"2025-04-21 12:09:22","post_modified_gmt":"2025-04-21 10:09:22","post_content_filtered":"","post_parent":"11222","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/foto-139_4713.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"14877"},{"ID":"14879","post_author":"2","post_date":"2025-03-07 23:22:21","post_date_gmt":"2025-03-07 22:22:21","post_content":"","post_title":"foto-139_4714","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"foto-139_4714","to_ping":"","pinged":"","post_modified":"2025-04-21 12:09:22","post_modified_gmt":"2025-04-21 10:09:22","post_content_filtered":"","post_parent":"11222","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/foto-139_4714.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"14879"},{"ID":"14881","post_author":"2","post_date":"2025-03-07 23:22:23","post_date_gmt":"2025-03-07 22:22:23","post_content":"","post_title":"foto-139_4715","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"foto-139_4715","to_ping":"","pinged":"","post_modified":"2025-04-21 12:09:22","post_modified_gmt":"2025-04-21 10:09:22","post_content_filtered":"","post_parent":"11222","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/foto-139_4715.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"14881"},{"ID":"14883","post_author":"2","post_date":"2025-03-07 23:22:25","post_date_gmt":"2025-03-07 22:22:25","post_content":"","post_title":"foto-139_4716","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"foto-139_4716","to_ping":"","pinged":"","post_modified":"2025-04-21 12:09:22","post_modified_gmt":"2025-04-21 10:09:22","post_content_filtered":"","post_parent":"11222","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/foto-139_4716.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"14883"},{"ID":"14885","post_author":"2","post_date":"2025-03-07 23:22:27","post_date_gmt":"2025-03-07 22:22:27","post_content":"","post_title":"foto-139_4717","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"foto-139_4717","to_ping":"","pinged":"","post_modified":"2025-04-21 12:09:22","post_modified_gmt":"2025-04-21 10:09:22","post_content_filtered":"","post_parent":"11222","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/foto-139_4717.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"14885"},{"ID":"14887","post_author":"2","post_date":"2025-03-07 23:22:29","post_date_gmt":"2025-03-07 22:22:29","post_content":"","post_title":"foto-139_4718","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"foto-139_4718","to_ping":"","pinged":"","post_modified":"2025-04-21 12:09:22","post_modified_gmt":"2025-04-21 10:09:22","post_content_filtered":"","post_parent":"11222","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/foto-139_4718.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"14887"},{"ID":"31319","post_author":"2","post_date":"2025-03-08 13:51:52","post_date_gmt":"2025-03-08 12:51:52","post_content":"","post_title":"puerta-de-c\u00f3rdoba_139_2","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"puerta-de-cordoba_139_2","to_ping":"","pinged":"","post_modified":"2025-04-21 12:09:22","post_modified_gmt":"2025-04-21 10:09:22","post_content_filtered":"","post_parent":"11222","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/puerta-de-cordoba_139_2.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"31319"},{"ID":"31321","post_author":"2","post_date":"2025-03-08 13:51:54","post_date_gmt":"2025-03-08 12:51:54","post_content":"","post_title":"puerta-de-c\u00f3rdoba_139_4","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"puerta-de-cordoba_139_4","to_ping":"","pinged":"","post_modified":"2025-04-21 12:09:22","post_modified_gmt":"2025-04-21 10:09:22","post_content_filtered":"","post_parent":"11222","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/puerta-de-cordoba_139_4.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"31321"},{"ID":"31323","post_author":"2","post_date":"2025-03-08 13:51:57","post_date_gmt":"2025-03-08 12:51:57","post_content":"","post_title":"puerta-de-c\u00f3rdoba_139_5","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"puerta-de-cordoba_139_5","to_ping":"","pinged":"","post_modified":"2025-04-21 12:09:22","post_modified_gmt":"2025-04-21 10:09:22","post_content_filtered":"","post_parent":"11222","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/puerta-de-cordoba_139_5.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"31323"},{"ID":"31325","post_author":"2","post_date":"2025-03-08 13:52:10","post_date_gmt":"2025-03-08 12:52:10","post_content":"","post_title":"puerta-de-c\u00f3rdoba_139_8","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"puerta-de-cordoba_139_8","to_ping":"","pinged":"","post_modified":"2025-04-21 12:09:22","post_modified_gmt":"2025-04-21 10:09:22","post_content_filtered":"","post_parent":"11222","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/puerta-de-cordoba_139_8.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"31325"},{"ID":"31327","post_author":"2","post_date":"2025-03-08 13:52:12","post_date_gmt":"2025-03-08 12:52:12","post_content":"","post_title":"puerta-de-c\u00f3rdoba_139_9","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"puerta-de-cordoba_139_9","to_ping":"","pinged":"","post_modified":"2025-04-21 12:09:22","post_modified_gmt":"2025-04-21 10:09:22","post_content_filtered":"","post_parent":"11222","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/puerta-de-cordoba_139_9.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"31327"},{"ID":"31329","post_author":"2","post_date":"2025-03-08 13:52:16","post_date_gmt":"2025-03-08 12:52:16","post_content":"","post_title":"puerta-de-c\u00f3rdoba_139_10","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"puerta-de-cordoba_139_10","to_ping":"","pinged":"","post_modified":"2025-04-21 12:09:22","post_modified_gmt":"2025-04-21 10:09:22","post_content_filtered":"","post_parent":"11222","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/puerta-de-cordoba_139_10.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"31329"},{"ID":"31331","post_author":"2","post_date":"2025-03-08 13:52:22","post_date_gmt":"2025-03-08 12:52:22","post_content":"","post_title":"puerta-de-c\u00f3rdoba_139_13","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"puerta-de-cordoba_139_13","to_ping":"","pinged":"","post_modified":"2025-04-21 12:09:22","post_modified_gmt":"2025-04-21 10:09:22","post_content_filtered":"","post_parent":"11222","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/puerta-de-cordoba_139_13.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"31331"},{"ID":"31333","post_author":"2","post_date":"2025-03-08 13:52:25","post_date_gmt":"2025-03-08 12:52:25","post_content":"","post_title":"puerta-de-c\u00f3rdoba_139_14","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"puerta-de-cordoba_139_14","to_ping":"","pinged":"","post_modified":"2025-04-21 12:09:22","post_modified_gmt":"2025-04-21 10:09:22","post_content_filtered":"","post_parent":"11222","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/puerta-de-cordoba_139_14.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"31333"}],"nombrepaginaes":"puerta-de-cordoba","nombrepaginaen":"puerta-de-cordoba","latitud_gps":"37\u00ba 28' 34.65","longitud_gps":"5\u00ba 38' 0.9","adicionaleses":"","adicionalesen":"","videoes":"","videoen":"","video2es":"","video2en":"","_links":{"self":[{"href":"https:\/\/spainfilmcommission.com\/en\/wp-json\/wp\/v2\/localizaciones\/localizacion\/11222","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/spainfilmcommission.com\/en\/wp-json\/wp\/v2\/localizaciones\/localizacion"}],"about":[{"href":"https:\/\/spainfilmcommission.com\/en\/wp-json\/wp\/v2\/types\/localizacion"}],"author":[{"embeddable":true,"href":"https:\/\/spainfilmcommission.com\/en\/wp-json\/wp\/v2\/users\/2"}],"wp:attachment":[{"href":"https:\/\/spainfilmcommission.com\/en\/wp-json\/wp\/v2\/media?parent=11222"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}