{"id":11199,"date":"2025-02-27T17:28:10","date_gmt":"2025-02-27T16:28:10","guid":{"rendered":"https:\/\/spainfilmcommission.com\/?post_type=localizacion&#038;p=11199"},"modified":"2025-04-21T13:03:35","modified_gmt":"2025-04-21T11:03:35","slug":"teatro-calderon-de-valladolid","status":"publish","type":"localizacion","link":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/teatro-calderon-de-valladolid\/","title":{"rendered":"Teatro Calder\u00f3n de Valladolid"},"content":{"rendered":"","protected":false},"author":2,"template":"","meta":[],"class_list":["post-11199","localizacion","type-localizacion","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rodar en Teatro Calder\u00f3n de Valladolid - Spain Film Commission<\/title>\n<meta name=\"description\" content=\"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Teatro Calder\u00f3n de Valladolid\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/spainfilmcommission.com\/en\/ai-locations\/teatro-calderon-de-valladolid\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rodar en Teatro Calder\u00f3n de Valladolid - Spain Film Commission\" \/>\n<meta property=\"og:description\" content=\"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Teatro Calder\u00f3n de Valladolid\" \/>\n<meta property=\"og:url\" content=\"https:\/\/spainfilmcommission.com\/en\/ai-locations\/teatro-calderon-de-valladolid\/\" \/>\n<meta property=\"og:site_name\" content=\"Spain Film Commission\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-21T11:03:35+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/ai-locations\\\/teatro-calderon-de-valladolid\\\/\",\"url\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/ai-locations\\\/teatro-calderon-de-valladolid\\\/\",\"name\":\"Rodar en Teatro Calder\u00f3n de Valladolid - Spain Film Commission\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#website\"},\"datePublished\":\"2025-02-27T16:28:10+00:00\",\"dateModified\":\"2025-04-21T11:03:35+00:00\",\"description\":\"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Teatro Calder\u00f3n de Valladolid\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/ai-locations\\\/teatro-calderon-de-valladolid\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/ai-locations\\\/teatro-calderon-de-valladolid\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/ai-locations\\\/teatro-calderon-de-valladolid\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Teatro Calder\u00f3n de Valladolid\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/\",\"name\":\"Spain Film Commission\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#organization\",\"name\":\"Spain Film Commission\",\"url\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/spainfilmcommission.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/SPC_COLOR.png\",\"contentUrl\":\"https:\\\/\\\/spainfilmcommission.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/SPC_COLOR.png\",\"width\":1665,\"height\":1665,\"caption\":\"Spain Film Commission\"},\"image\":{\"@id\":\"https:\\\/\\\/spainfilmcommission.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rodar en Teatro Calder\u00f3n de Valladolid - Spain Film Commission","description":"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Teatro Calder\u00f3n de Valladolid","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/teatro-calderon-de-valladolid\/","og_locale":"en_US","og_type":"article","og_title":"Rodar en Teatro Calder\u00f3n de Valladolid - Spain Film Commission","og_description":"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Teatro Calder\u00f3n de Valladolid","og_url":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/teatro-calderon-de-valladolid\/","og_site_name":"Spain Film Commission","article_modified_time":"2025-04-21T11:03:35+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/teatro-calderon-de-valladolid\/","url":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/teatro-calderon-de-valladolid\/","name":"Rodar en Teatro Calder\u00f3n de Valladolid - Spain Film Commission","isPartOf":{"@id":"https:\/\/spainfilmcommission.com\/en\/#website"},"datePublished":"2025-02-27T16:28:10+00:00","dateModified":"2025-04-21T11:03:35+00:00","description":"En esta p\u00e1gina encontrar\u00e1s una peque\u00f1a descripci\u00f3n, m\u00e1genes e informaci\u00f3n relevante para que te hagas una idea de c\u00f3mo es rodar en Teatro Calder\u00f3n de Valladolid","breadcrumb":{"@id":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/teatro-calderon-de-valladolid\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/spainfilmcommission.com\/en\/ai-locations\/teatro-calderon-de-valladolid\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/spainfilmcommission.com\/en\/ai-locations\/teatro-calderon-de-valladolid\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/spainfilmcommission.com\/en\/"},{"@type":"ListItem","position":2,"name":"Teatro Calder\u00f3n de Valladolid"}]},{"@type":"WebSite","@id":"https:\/\/spainfilmcommission.com\/en\/#website","url":"https:\/\/spainfilmcommission.com\/en\/","name":"Spain Film Commission","description":"","publisher":{"@id":"https:\/\/spainfilmcommission.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/spainfilmcommission.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/spainfilmcommission.com\/en\/#organization","name":"Spain Film Commission","url":"https:\/\/spainfilmcommission.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/spainfilmcommission.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2024\/07\/SPC_COLOR.png","contentUrl":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2024\/07\/SPC_COLOR.png","width":1665,"height":1665,"caption":"Spain Film Commission"},"image":{"@id":"https:\/\/spainfilmcommission.com\/en\/#\/schema\/logo\/image\/"}}]}},"socio":[{"ID":"17","user_login":"valladolid-film-commission","user_nicename":"valladolid-film-commission","display_name":"valladolid-film-commission","user_pass":"****************","user_email":"filmcommission@valladolidturismo.com","user_url":"","user_registered":"2024-12-19 13:46:02","id":17}],"nombrees":"Teatro Calder\u00f3n de Valladolid","nombreen":"Teatro Calder\u00f3n de Valladolid","localidad":"Valladolid","provincia":"Valladolid","coordenadas_maps":"41.6539, -4.72437","latitud":"41.653900000000","longitud":"-4.724370000000","direcciones":"C\/ Angustias, 1","direccionen":"C\/ Angustias, 1","cod_postal":"47003","telefono":"(+34) 983","fax":"","mail":"filmoffice@valladolidturismo.com","web":"http:\/\/www.tcalderon.com\/","descripciones":"Teatro ubicado en el casco hist\u00f3rico de Valladolid (Castilla y Le\u00f3n). Cumple con los esquemas de dise\u00f1o de un teatro de estilo neocl\u00e1sico. Consta de un gran soportal en la fachada principal y con amplios ventanales en las plantas superiores. En el interior cuenta con una sala principal en forma de herradura, con patio de butacas, palcos bajos, platea, anfiteatro, galer\u00eda y para\u00edso. De su decoraci\u00f3n destacan lujosas pinturas obra de Augusto Ferri y l\u00e1mparas laterales, de estilo modernista. En 1999 fue reformado y modernizado sin perder el estilo cl\u00e1sico.","descripcionen":"The theater is located in the historical center of Valladolid (Castile and Leon). Its design is that of a typical neoclassical theatre, with a great portico in the main facade and large windows on the top floors. The interior follows a horseshoe shape, which encompasses a parterre, the low theater boxes, an orchestra, the amphitheatre, gallery and paradise. Within its decorations Augustus Ferri\u2019s luxiurios paintings and the art deco lateral lamps stand out. In 1999 it was reformed and modernized without losing its classical style.","galeria":[{"ID":"31823","post_author":"2","post_date":"2025-03-08 14:08:35","post_date_gmt":"2025-03-08 13:08:35","post_content":"","post_title":"teatro-calder\u00f3n_113_1","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"teatro-calderon_113_1","to_ping":"","pinged":"","post_modified":"2025-04-21 13:03:35","post_modified_gmt":"2025-04-21 11:03:35","post_content_filtered":"","post_parent":"11199","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/teatro-calderon_113_1.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"31823"},{"ID":"31825","post_author":"2","post_date":"2025-03-08 14:08:41","post_date_gmt":"2025-03-08 13:08:41","post_content":"","post_title":"teatro-calder\u00f3n_113_2","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"teatro-calderon_113_2","to_ping":"","pinged":"","post_modified":"2025-04-21 13:03:36","post_modified_gmt":"2025-04-21 11:03:36","post_content_filtered":"","post_parent":"11199","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/teatro-calderon_113_2.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"31825"},{"ID":"31827","post_author":"2","post_date":"2025-03-08 14:08:44","post_date_gmt":"2025-03-08 13:08:44","post_content":"","post_title":"teatro-calder\u00f3n_113_3","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"teatro-calderon_113_3","to_ping":"","pinged":"","post_modified":"2025-04-21 13:03:36","post_modified_gmt":"2025-04-21 11:03:36","post_content_filtered":"","post_parent":"11199","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/teatro-calderon_113_3.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"31827"},{"ID":"31829","post_author":"2","post_date":"2025-03-08 14:08:48","post_date_gmt":"2025-03-08 13:08:48","post_content":"","post_title":"teatro-calder\u00f3n_113_4","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"teatro-calderon_113_4","to_ping":"","pinged":"","post_modified":"2025-04-21 13:03:36","post_modified_gmt":"2025-04-21 11:03:36","post_content_filtered":"","post_parent":"11199","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/teatro-calderon_113_4.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"31829"},{"ID":"31831","post_author":"2","post_date":"2025-03-08 14:08:55","post_date_gmt":"2025-03-08 13:08:55","post_content":"","post_title":"teatro-calder\u00f3n_113_5","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"teatro-calderon_113_5","to_ping":"","pinged":"","post_modified":"2025-04-21 13:03:36","post_modified_gmt":"2025-04-21 11:03:36","post_content_filtered":"","post_parent":"11199","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/teatro-calderon_113_5.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"31831"},{"ID":"31833","post_author":"2","post_date":"2025-03-08 14:08:58","post_date_gmt":"2025-03-08 13:08:58","post_content":"","post_title":"teatro-calder\u00f3n_113_6","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"teatro-calderon_113_6","to_ping":"","pinged":"","post_modified":"2025-04-21 13:03:36","post_modified_gmt":"2025-04-21 11:03:36","post_content_filtered":"","post_parent":"11199","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/teatro-calderon_113_6.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"31833"},{"ID":"31835","post_author":"2","post_date":"2025-03-08 14:09:02","post_date_gmt":"2025-03-08 13:09:02","post_content":"","post_title":"teatro-calder\u00f3n_113_7","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"teatro-calderon_113_7","to_ping":"","pinged":"","post_modified":"2025-04-21 13:03:36","post_modified_gmt":"2025-04-21 11:03:36","post_content_filtered":"","post_parent":"11199","guid":"https:\/\/spainfilmcommission.com\/wp-content\/uploads\/2025\/03\/teatro-calderon_113_7.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"31835"}],"nombrepaginaes":"teatro-calderon-de-valladolid","nombrepaginaen":"teatro-calderon-de-valladolid","latitud_gps":"41\u00ba 39\u00b4 15\u00b4\u00b4 N","longitud_gps":"4\u00ba 43\u00b429\u00b4\u00b4 O","adicionaleses":"","adicionalesen":"","videoes":"","videoen":"","video2es":"","video2en":"","_links":{"self":[{"href":"https:\/\/spainfilmcommission.com\/en\/wp-json\/wp\/v2\/localizaciones\/localizacion\/11199","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/spainfilmcommission.com\/en\/wp-json\/wp\/v2\/localizaciones\/localizacion"}],"about":[{"href":"https:\/\/spainfilmcommission.com\/en\/wp-json\/wp\/v2\/types\/localizacion"}],"author":[{"embeddable":true,"href":"https:\/\/spainfilmcommission.com\/en\/wp-json\/wp\/v2\/users\/2"}],"wp:attachment":[{"href":"https:\/\/spainfilmcommission.com\/en\/wp-json\/wp\/v2\/media?parent=11199"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}